{"id":1242,"date":"2026-02-26T21:03:40","date_gmt":"2026-02-27T04:03:40","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1242"},"modified":"2026-02-26T21:03:44","modified_gmt":"2026-02-27T04:03:44","slug":"anuncia-imca-la-proxima-edicion-de-creactiva-v-encuentro-de-mujeres-en-las-artes","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/02\/26\/anuncia-imca-la-proxima-edicion-de-creactiva-v-encuentro-de-mujeres-en-las-artes\/","title":{"rendered":"Anuncia IMCA la pr\u00f3xima edici\u00f3n de Creactiva. V Encuentro de Mujeres en las Artes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Gobierno Municipal y sociedad civil se unen para reconocer el trabajo de creadoras y gestoras culturales hermosillenses en diferentes disciplinas art\u00edsticas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">No. 2028\/2026<br>Hermosillo, Sonora; 26 de febrero, 2026.- El Ayuntamiento de Hermosillo, a trav\u00e9s del Instituto Municipal de Cultura y Arte, conmemorar\u00e1 el D\u00eda Internacional de la Mujer con un programa de actividades a realizarse del 4 al 7 de marzo en el marco de Creactiva. V Encuentro de Mujeres en las Artes, anunci\u00f3 Marianna Gonz\u00e1lez Gast\u00e9lum, directora general del Instituto Municipal de Cultura y Arte (IMCA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comparti\u00f3 los detalles de la quinta edici\u00f3n del encuentro, acompa\u00f1ada por Zulma Galaz Angulo, directora de Atenci\u00f3n a la Mujer y Mar\u00eda Luisa Verdugo Lucero, gerente administrativo de Galer\u00eda Oasis 179.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesde IMCA, a trav\u00e9s del programa Cultura Incluyente, trabajamos para que el acceso al arte y la cultura sea m\u00e1s amplio y diverso, Creactiva es justamente eso: un espacio de encuentro, di\u00e1logo y expresi\u00f3n para mujeres creadoras y gestoras culturales\u201d, afirm\u00f3 Marianna Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esta edici\u00f3n de Creactiva se contar\u00e1 con la participaci\u00f3n de m\u00e1s 120 mujeres, en actividades como exposiciones, presentaciones musicales, talleres, conferencias, obras de teatro, presentaciones de libros, degustaci\u00f3n de comida tradicional yaqui y exhibici\u00f3n de artesan\u00eda seri\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Invit\u00f3 a la ciudadan\u00eda en general a consultar las redes sociales del IMCA y del Ayuntamiento de Hermosillo, as\u00ed como la p\u00e1gina http:\/\/imca.hermosillo.gob.mx para conocer el programa completo y las distintas sedes donde se desarrollar\u00e1n las actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Zulma Galaz Angulo anunci\u00f3 la \u201cRodada por las Mujeres\u201d que se efectuar\u00e1 el pr\u00f3ximo domingo 8 de marzo, D\u00eda Internacional de la Mujer, con invitaci\u00f3n abierta a todas las personas que deseen sumarse, a quienes invit\u00f3 a registrarse en el formato que estar\u00e1 disponible en la liga: forms.gle\/rhFmR12S3YPLJwtR9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto de partida y meta ser\u00e1 la Plaza de los 100 A\u00f1os, sobre la calle Rosales, con trayecto de ida y vuelta por las ciclov\u00edas del bulevar Colosio, entre la calle Rosales y el bulevar Solidaridad, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gerente administrativa de la Galer\u00eda Oasis 179, invit\u00f3 a la inauguraci\u00f3n de la exposici\u00f3n colectiva \u201cCaleidoscopio de Mujeres\u201d, que se realizar\u00e1 el mi\u00e9rcoles 4 de marzo, a las 19:00 horas, donde se contar\u00e1 con la participaci\u00f3n de m\u00e1s de 40 artistas visuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datos:<br>-Colaborar\u00e1n varias dependencias del Ayuntamiento: Direcci\u00f3n General de Atenci\u00f3n a la Mujer, Instituto del Deporte de Hermosillo (IDH), DIF Hermosillo, as\u00ed como Galer\u00eda Oasis 179, Andamios Teatro, Conservatorio de M\u00fasica L\u2019Orfeo, Lormiga T\u00edteres y Hebras Cact\u00e1ceas.<br>-Por tercer a\u00f1o consecutivo se realizar\u00e1 la Mesa de reflexi\u00f3n \u201cMujeres compartiendo arte\u201d, en el que creadoras y gestoras culturales de Hermosillo dialogar\u00e1n sobre sus procesos creativos, las oportunidades y los retos a los que se enfrentan en las diversas disciplinas art\u00edsticas. Tambi\u00e9n participar\u00e1n en el taller Autoestima para mujeres artistas, impartido por Blanca Susan Chico y Fernanda Galindo.<br>-Habr\u00e1 degustaci\u00f3n de comida tradicional yaqui, a cargo de Griselda Figueroa Moreno y exhibici\u00f3n de artesan\u00eda seri, a cargo de Guillermina Barnett D\u00edaz.<br>-La soprano Marian Zamorano, acompa\u00f1ada del pianista Emmanuel Sab\u00e1s, ofrecer\u00e1 el recital de canto l\u00edrico Vida y amor de mujer, en Galer\u00eda Oasis 179.<br>-En Parque Madero, se presentar\u00e1n los libros de autoras como Julia Melissa Rivas y Sarina Pedroza, as\u00ed como la obra de teatro Zumbido, con Ana Paula Ornelas, Meztli Montero y Carolina Ortega.<br>-Andamios Teatro presentar\u00e1 de la obra Desaz\u00f3n, con Adriana Figueroa y H\u00e9ctor Acosta. Mientras que la agrupaci\u00f3n musical Luces de Venus ofrecer\u00e1 un concierto con composiciones de su autor\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"733\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.08-PM-1-1024x733.jpeg\" alt=\"\" class=\"wp-image-1243\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.08-PM-1-1024x733.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.08-PM-1-300x215.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.08-PM-1-768x550.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.08-PM-1.jpeg 1168w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/INSERT-MARIANA-GONZALEZ-IMCA-EVENTO-CREATIVA.mp4\"><\/video><\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/PROGRAMA-CREACTIVA-V-ENCUENTRO-DE-MUJERES-EN-LAS-ARTES.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de PROGRAMA CREACTIVA V ENCUENTRO DE MUJERES EN LAS ARTES.\"><\/object><a id=\"wp-block-file--media-be414742-7887-421f-9ee7-21c72f867871\" href=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/PROGRAMA-CREACTIVA-V-ENCUENTRO-DE-MUJERES-EN-LAS-ARTES.pdf\">PROGRAMA CREACTIVA V ENCUENTRO DE MUJERES EN LAS ARTES<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>-Gobierno Municipal y sociedad civil se unen para reconocer el trabajo de creadoras y gestoras culturales hermosillenses en diferentes disciplinas art\u00edsticas.<\/p>\n","protected":false},"author":1,"featured_media":1240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,30],"tags":[],"class_list":["post-1242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1242"}],"version-history":[{"count":2,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1242\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1242\/revisions\/1247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1240"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}