{"id":1248,"date":"2026-02-26T21:08:24","date_gmt":"2026-02-27T04:08:24","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1248"},"modified":"2026-02-26T21:08:51","modified_gmt":"2026-02-27T04:08:51","slug":"invita-gobierno-de-hermosillo-a-la-octava-edicion-de-hermosillo-crece-con-empleo","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/02\/26\/invita-gobierno-de-hermosillo-a-la-octava-edicion-de-hermosillo-crece-con-empleo\/","title":{"rendered":"Invita Gobierno de Hermosillo a la Octava Edici\u00f3n de Hermosillo Crece con Empleo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-El 11 de marzo pr\u00f3ximo se fusionar\u00e1n la Expo Empleo 2026 y Hermosillo Crece con Empleo con el objetivo en com\u00fan de vincular a la oferta y la demanda laboral.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">No. 2029\/2026<br>Hermosillo, Sonora; 26 de febrero, 2026.- Personas en Hermosillo, que est\u00e9n en busca de colocarse en un empleo formal, el pr\u00f3ximo mi\u00e9rcoles 11 de marzo tendr\u00e1n la oportunidad de aplicar para los puestos administrativos, operativos, y para personas con discapacidad, que estar\u00e1n ofreciendo m\u00e1s de 30 empresas en la Octava Feria Hermosillo Crece con Empleo y Expo Empleo 2026, anunci\u00f3 Oscar Gast\u00e9lum Donnadieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director de la Agencia Municipal de Desarrollo Econ\u00f3mico (AMDE) comparti\u00f3 detalles del evento junto con Iv\u00e1n Contreras Tapia y Jos\u00e9 Jes\u00fas Aguiar Varela, presidente y director de Canacintra Hermosillo, respectivamente, quienes confirmaron como sede las instalaciones del organismo empresarial, en Luis Encinas 460 de la colonia Los Naranjos, de las 9:00 a las 14:00 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cObviamente el objetivo de esta feria, de esta expo, es vincular estas vacantes con las personas que asistan, en busca de estas oportunidades, pero tambi\u00e9n queremos preparar mejor a las personas que asistan para que puedan aumentar sus probabilidades de conseguir estas oportunidades de empleo y dado a eso vamos a llevar a cabo cursos gratuitos en Canacintra los d\u00edas lunes 9 de marzo y martes 10 de marzo\u201d, explic\u00f3 el director de la AMDE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las capacitaciones ser\u00e1n de las 10:00 a las 13:00 horas, ambos d\u00edas, en aspectos como preparar una buena entrevista laboral y un curr\u00edculum, desarrollo de ciertas habilidades personales y para el manejo del estr\u00e9s laboral, as\u00ed como el uso de la Inteligencia Artificial en el trabajo, abund\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que el Gobierno Municipal que encabeza Antonio Astiazar\u00e1n continuar\u00e1 trabajando en alianza con el sector empresarial para que el crecimiento econ\u00f3mico del municipio se traduzca en oportunidades reales de empleo, y con ello de prosperidad, para la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de Canacintra en Hermosillo afirm\u00f3 que la Expo Empleo 2026 busca no s\u00f3lo hacer coincidir la oferta con la demanda laboral, sino tambi\u00e9n elevar la competitividad del talento sonorense al ofrecerle herramientas alineadas a las nuevas din\u00e1micas del mercado laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como medios de contacto, tanto para aspirantes a colocarse laboralmente como potenciales contratantes que quieran enviar a su personal reclutador, ofrecieron el n\u00famero de Whatsapp 6622 332019 y todas las redes sociales de Canacintra Hermosillo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"657\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-1024x657.jpeg\" alt=\"\" class=\"wp-image-1250\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-1024x657.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-300x193.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-768x493.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-1536x986.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-26-at-8.32.30-PM-1-2048x1315.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/INSERT-OSCAR-GASTELUM-ECONOMIA-FERIA-DEL-EMPLEO.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>-El 11 de marzo pr\u00f3ximo se fusionar\u00e1n la Expo Empleo 2026 y Hermosillo Crece con Empleo con el objetivo en com\u00fan de vincular a la oferta y la demanda laboral.<\/p>\n","protected":false},"author":1,"featured_media":1249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,30],"tags":[],"class_list":["post-1248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1248"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1248\/revisions"}],"predecessor-version":[{"id":1252,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1248\/revisions\/1252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1249"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}