{"id":1309,"date":"2026-02-27T17:00:32","date_gmt":"2026-02-28T00:00:32","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1309"},"modified":"2026-02-27T17:00:36","modified_gmt":"2026-02-28T00:00:36","slug":"estudiante-de-cecyte-representara-a-sonora-en-competencia-nacional-de-box-conade-2026","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/02\/27\/estudiante-de-cecyte-representara-a-sonora-en-competencia-nacional-de-box-conade-2026\/","title":{"rendered":"Estudiante de Cecyte representar\u00e1 a Sonora en Competencia Nacional de Box Conade 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 27 de febrero de 2026.\u2013 Jos\u00e9 Aar\u00f3n P\u00e1ez Lizardo, estudiante de segundo semestre del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Sonora (Cecyte Sonora), plantel Nogales I, participar\u00e1 en los Juegos Nacionales Conade, que se celebrar\u00e1n en el estado de Chihuahua del 18 al 21 de marzo.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">El alumno asegur\u00f3 su pase a la etapa nacional del 11 al 13 de febrero, durante la competencia realizada en Hermosillo, Sonora. Con ocho a\u00f1os de trayectoria deportiva, se prepara para poner en alto el nombre de Sonora en esta importante justa nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora general de Cecyte Sonora, Blanca Aurelia Valenzuela, destac\u00f3 que Jos\u00e9 Aar\u00f3n ha sabido compaginar sus estudios con el deporte, teniendo en su padre a su principal fuente de inspiraci\u00f3n, quien lo ha motivado a dar siempre lo mejor de s\u00ed. Actualmente cursa la carrera de Programaci\u00f3n en el plantel Nogales I.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de su trayectoria, ha participado en diversas competencias, consolid\u00e1ndose como campe\u00f3n municipal, bicampe\u00f3n regional y campe\u00f3n estatal. Asimismo, obtuvo el segundo lugar en el torneo Guerra en la Frontera y ha competido en eventos como Guantes de Oro, Perla del Desierto, Armageddon y Guerra de Estados, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus principales metas acad\u00e9micas se encuentra estudiar Criminolog\u00eda al egresar de Cecyte. En el \u00e1mbito deportivo, aspira a representar a M\u00e9xico en los Juegos Ol\u00edmpicos, debutar como profesional y convertirse en campe\u00f3n mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cecyte reafirma as\u00ed el compromiso del Gobierno de Sonora con la juventud sonorense, impulsando la educaci\u00f3n y el deporte como factores fundamentales para alejar a las y los j\u00f3venes de las adicciones y de situaciones que puedan afectar su desarrollo integral.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM-1024x575.jpeg\" alt=\"\" class=\"wp-image-1311\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM-1024x575.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM-300x168.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM-768x431.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM-1536x862.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-27-at-4.43.52-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 27 de febrero de 2026.\u2013 Jos\u00e9 Aar\u00f3n P\u00e1ez Lizardo, estudiante de segundo semestre del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Sonora (Cecyte Sonora), plantel Nogales I, participar\u00e1 en los Juegos Nacionales Conade, que se celebrar\u00e1n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-1309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1309"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1309\/revisions"}],"predecessor-version":[{"id":1312,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1309\/revisions\/1312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1310"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}