{"id":1547,"date":"2026-03-03T20:28:08","date_gmt":"2026-03-04T03:28:08","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1547"},"modified":"2026-03-03T20:28:12","modified_gmt":"2026-03-04T03:28:12","slug":"plantea-sebastian-orduno-acciones-afirmativas-en-favor-de-mujeres-cuidadoras","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/03\/plantea-sebastian-orduno-acciones-afirmativas-en-favor-de-mujeres-cuidadoras\/","title":{"rendered":"Plantea Sebasti\u00e1n Ordu\u00f1o acciones afirmativas en favor de mujeres cuidadoras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Se establecen medidas concretas para cerrar brechas de g\u00e9nero en el \u00e1mbito del cuidado.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 3 de marzo de 2026.- Para avanzar hacia una verdadera igualdad sustantiva, el diputado Sebasti\u00e1n Ordu\u00f1o Fragoza present\u00f3 una iniciativa de Ley de Apoyo Integral a Mujeres Cuidadoras del Estado de Sonora, con la finalidad de brindar apoyo directo y reconocimiento a quienes desempe\u00f1an tareas de cuidado sin recibir remuneraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado destac\u00f3 que las labores de cuidado son fundamentales para el funcionamiento de la sociedad y el bienestar de las familias; sin embargo, siguen siendo actividades poco reconocidas y no remuneradas, que recaen principalmente en las mujeres. Esta realidad, se\u00f1al\u00f3, restringe sus oportunidades de incorporarse al mercado laboral formal, afecta su autonom\u00eda econ\u00f3mica y ampl\u00eda las desigualdades existentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta ley constituye una acci\u00f3n afirmativa, objetiva y proporcional orienta a reducir la vulnerabilidad econ\u00f3mica y social que enfrentan las mujeres cuidadoras primarias. Ello no implica desconocer la existencia de hombres cuidadores, sino atender al grupo que estad\u00edsticamente concentra la mayor carga estructural asociada al cuidado remunerado\u201d, mencion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ordu\u00f1o Fragoza explic\u00f3 que de acuerdo con informaci\u00f3n del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI), las mujeres destinan m\u00e1s del doble de horas que los hombres al trabajo dom\u00e9stico y de cuidados no remunerado, lo que impacta directamente en su autonom\u00eda econ\u00f3mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa contempla la creaci\u00f3n de un Registro Estatal de Mujeres Cuidadoras y un Programa Estatal de Apoyo Integral, bajo la coordinaci\u00f3n de la Secretar\u00eda de Bienestar Social, con reglas de operaci\u00f3n claras, criterios de priorizaci\u00f3n objetivos y evaluaci\u00f3n anual de resultados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que la iniciativa tiene como fundamento el principio de igualdad sustantiva establecido en la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, as\u00ed como en precedentes de la Suprema Corte de Justicia de la Naci\u00f3n que respaldan la adopci\u00f3n de medidas afirmativas para atender y revertir desigualdades estructurales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Establece, adem\u00e1s, la obligaci\u00f3n de presentar informes anuales al Congreso con indicadores de impacto y garantizar la previsi\u00f3n presupuestal progresiva para su implementaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta propuesta, el legislador afirm\u00f3 que Sonora puede dar un paso firme hacia una pol\u00edtica p\u00fablica que reconozca el derecho al cuidado y fortalezca la autonom\u00eda econ\u00f3mica de las mujeres cuidadoras en la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Iniciativa fue turnada a la Comisi\u00f3n de Bienestar Social para su estudio y posterior dictaminaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Se establecen medidas concretas para cerrar brechas de g\u00e9nero en el \u00e1mbito del cuidado.<\/p>\n","protected":false},"author":1,"featured_media":1548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-1547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"predecessor-version":[{"id":1549,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1547\/revisions\/1549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1548"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}