{"id":1595,"date":"2026-03-04T20:58:14","date_gmt":"2026-03-05T03:58:14","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1595"},"modified":"2026-03-05T21:36:25","modified_gmt":"2026-03-06T04:36:25","slug":"la-era-trump-colapsa-a-la-organizacion-de-las-naciones-unidas","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/04\/la-era-trump-colapsa-a-la-organizacion-de-las-naciones-unidas\/","title":{"rendered":"LA ERA TRUMP COLAPSA A LA ORGANIZACI\u00d3N DE LAS NACIONES UNIDAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nunca nos imaginamos que escribir\u00edamos que la Organizaci\u00f3n de las Naciones Unidas, ONU, ha dejado de ser la principal instituci\u00f3n internacional para mantener la paz, promover la cooperaci\u00f3n internacional y proteger los derechos humanos en todo el mundo, como consecuencia de colapso que le ha infringido la era Trump, como ahora lo afirmamos no sin antes lamentarlo profundamente.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">La ONU, recordemos, fue establecida el 24 de octubre de 1945, tras la Segunda Guerra Mundial, mediante la firma de la Carta de las Naciones Unidas por 51 Estados miembros, incluyendo M\u00e9xico. Su creaci\u00f3n reemplaz\u00f3 a la Sociedad de Naciones, que no logr\u00f3 evitar conflictos internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donald Trump desde su primer periodo empez\u00f3 a torpedear al organismo mundial al sacar a Estados Unidos de varias de sus instituciones y ahora ha multiplicado esa decisi\u00f3n porque seg\u00fan su criterio \u201cno sirven a nuestros intereses\u201d, la potencia mundial se ha retirado de m\u00e1s de 60 organizaciones internacionales, convenciones y tratados, a ello agr\u00e9guese que el magnate busca sustituir a la ONU, por su \u201cjunta de paz\u201d, seg\u00fan expertos podr\u00eda no tener futuro, pero el da\u00f1o al organismo mundial es un hecho cierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propia presidenta, Claudia Sheinbaum Pardo ha se\u00f1alado que \u201cla ONU dej\u00f3 de cumplir su labor\u201d ante los conflictos en Medio Oriente y el mundo, al advertir que la Organizaci\u00f3n de las Naciones Unidas ha perdido fuerza frente a decisiones de potencias militares y reiter\u00f3 que la poblaci\u00f3n civil es la principal v\u00edctima de esos conflictos en Medio Oriente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de M\u00e9xico lament\u00f3 la p\u00e9rdida de fuerza por parte de la ONU, donde incluso, se\u00f1al\u00f3 que, la organizaci\u00f3n hab\u00eda dejado de cumplir con su deber principal, esto frente a los recientes ataques contra Ir\u00e1n que Estados Unidos e Israel han llevado a cabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria acus\u00f3 que la falta de acci\u00f3n por parte de la Organizaci\u00f3n mundial ha provocado que la poblaci\u00f3n civil sufra las consecuencias de este tipo de conflictos, desde luego exhort\u00f3 a la organizaci\u00f3n para que act\u00fae \u201ctiene que hacer algo para recuperar su poder y su papel principal en la diplomacia de los pa\u00edses\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante los recientes ataques en contra de Ir\u00e1n, la Jefa del Ejecutivo mexicano, precisamente tras los hechos ocurridos el s\u00e1bado 28 de febrero, el ataque realizado por Estados Unidos e Israel hacia Ir\u00e1n, reafirm\u00f3 la postura que tiene su actual gobierno frente a los conflictos internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que M\u00e9xico siempre va a luchar por la paz en cualquier momento y bajo cualquier circunstancia. Adem\u00e1s, inform\u00f3 que nuestro pa\u00eds defender\u00e1 permanentemente los valores como la autodeterminaci\u00f3n de los pueblos, la no intervenci\u00f3n, la igualdad jur\u00eddica de los Estados y la cooperaci\u00f3n internacional para el desarrollo, principios fundamentales de la pol\u00edtica exterior mexicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, la presidenta subray\u00f3 que el titular del Ejecutivo debe observar estos lineamientos ante la proscripci\u00f3n de amenazas o del uso de la fuerza, as\u00ed como en la lucha por la paz y la seguridad internacional, recordando que dichos valores constituyen ejes inamovibles de la diplomacia mexicana desde 1914, momento en el que se defendi\u00f3 la soberan\u00eda ante invasiones extranjeras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y remat\u00f3, desde su conferencia en Palacio Nacional, frente al aumento de la violencia en Medio Oriente, al criticar la inacci\u00f3n de la Organizaci\u00f3n de las Naciones Unidas, al se\u00f1alar que \u201cno cumple con el papel bajo el cual fue creada\u201d, pues consider\u00f3 que \u201cactualmente predominan las decisiones de los pa\u00edses con mayor poder militar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las declaraciones de la presidenta de M\u00e9xico, la ONU ha perdido influencia ante las decisiones y conflictos de los pa\u00edses a nivel mundial. Derivado de ello, la principal consecuencia afecta a la poblaci\u00f3n civil, que es la que m\u00e1s sufre por este tipo de ataques. Se\u00f1al\u00f3 que \u201ces triste lo que ocurre, por decir lo menos; ya que la poblaci\u00f3n es quien lo paga\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta tambi\u00e9n aprovech\u00f3 para recordar que la intenci\u00f3n de la ONU tras la Segunda Guerra Mundial era asegurar que todos los pa\u00edses tuvieran voz y voto en los asuntos internacionales, por desgracia y lamentable por todos los conceptos que esto ocurra con todas las consecuencias apocal\u00edpticas que pudiera engendrar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LA ERA TRUMP COLAPSA A LA ORGANIZACI\u00d3N DE LAS NACIONES UNIDAS.<br>Periodista y escritor; presidente del Colegio Nacional de Licenciados en Periodismo, CONALIPE; secretario de Desarrollo Social de la Federaci\u00f3n Latinoamericana de Periodistas, FELAP; presidente fundador y vitalicio honorario de la Federaci\u00f3n de Asociaciones de Periodistas Mexicanos, FAPERMEX, Doctor Honoris Causa por la Universidad Internacional, Acad\u00e9mico de N\u00famero y Director de Comunicaci\u00f3n de la Academia Nacional de Historia y Geograf\u00eda, ANHG. Agradecer\u00e9 sus comentarios y cr\u00edticas en teodororenteriaa@gmail.com Nos escuchamos en las frecuencias en toda la Rep\u00fablica de Libertas Radio. Le invitamos a visitar: www.felap.info, www.ciap-felap.org, www.fapermex.org, y el portal: www.irradianoticias.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nunca nos imaginamos que escribir\u00edamos que la Organizaci\u00f3n de las Naciones Unidas, ONU, ha dejado de ser la principal instituci\u00f3n internacional para mantener la paz, promover la cooperaci\u00f3n internacional y proteger los derechos humanos en todo el mundo, como consecuencia&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[93],"tags":[],"class_list":["post-1595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1595"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1595\/revisions"}],"predecessor-version":[{"id":1597,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1595\/revisions\/1597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1629"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}