{"id":1646,"date":"2026-03-05T22:02:51","date_gmt":"2026-03-06T05:02:51","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1646"},"modified":"2026-03-05T22:02:56","modified_gmt":"2026-03-06T05:02:56","slug":"mas-de-300-envoltorios-de-narcotico-son-asegurados-en-estrategia-de-seguridad-de-la-policia-estatal","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/05\/mas-de-300-envoltorios-de-narcotico-son-asegurados-en-estrategia-de-seguridad-de-la-policia-estatal\/","title":{"rendered":"M\u00e1s de 300 envoltorios de narc\u00f3tico son asegurados en estrategia de seguridad de la Polic\u00eda Estatal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 5 de marzo de 2026.- Fuerzas operativas de la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) generaron importantes aseguramientos en municipios de Sonora como parte del trabajo de combate al delito. Durante las acciones realizadas el mi\u00e9rcoles, aseguraron a 16 personas y sacaron de las calles alrededor de 336 envoltorios con narc\u00f3tico.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Durante los patrullajes se obtuvieron los siguientes resultados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hermosillo: en la colonia Las Minitas se incautaron 22 envoltorios de sustancia prohibida en una acci\u00f3n coordinada con la Secretar\u00eda de la Defensa Nacional (Defensa). En Villas del Real detuvieron a Javier \u201cN\u201d en posesi\u00f3n de un arma blanca y 20 envoltorios con materia granulada.<\/li>\n\n\n\n<li>En la colonia Fovissste fue sorprendido Jos\u00e9 \u201cN\u201d con seis paquetes con hierba verde, mientras que en Jacinto L\u00f3pez fue detenido Manuel \u201cN\u201d con una bolsa con sustancia granulada de la cual se podr\u00edan confeccionar alrededor de 50 dosis. Tambi\u00e9n se registraron aseguramientos en las colonias Palo Verde, Los Arroyos, Proyecto Altares, Centro y Ley 57.<\/li>\n\n\n\n<li>Caborca: durante recorridos de vigilancia coordinados con Polic\u00eda Municipal, en el tramo de terracer\u00eda Plutarco El\u00edas Calles\u2013Puerto Pe\u00f1asco fue detenida Ana \u201cN\u201d con 13 envoltorios con narc\u00f3tico.<\/li>\n\n\n\n<li>Nogales: en coordinaci\u00f3n con la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) y la Agencia Ministerial de Investigaci\u00f3n Criminal, fue detenido Gabriel \u201cN\u201d, a quien le aseguraron 20 envoltorios con narc\u00f3tico en la colonia La Mesa.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cinco veh\u00edculos con reporte de robo fueron recuperados en diferentes zonas del estado: Hermosillo, poblado Miguel Alem\u00e1n, Empalme, Cajeme y Nogales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada una de las personas detenidas fue informada sobre sus derechos, quedando a disposici\u00f3n del Ministerio P\u00fablico para los tr\u00e1mites legales correspondientes. La PESP reitera el llamado a la ciudadan\u00eda para denunciar el delito a la l\u00ednea an\u00f3nima 089.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota: Las personas detenidas se presumen inocentes y ser\u00e1n tratadas como tales en todas las etapas del procedimiento, mientras no se declare su responsabilidad mediante sentencia emitida por el \u00f3rgano jurisdiccional correspondiente, conforme a lo establecido en el art\u00edculo 13 del C\u00f3digo Nacional de Procedimientos Penales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 5 de marzo de 2026.- Fuerzas operativas de la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) generaron importantes aseguramientos en municipios de Sonora como parte del trabajo de combate al delito. Durante las acciones realizadas el mi\u00e9rcoles, aseguraron a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,91,88],"tags":[],"class_list":["post-1646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policiaca","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1646"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1646\/revisions"}],"predecessor-version":[{"id":1648,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1646\/revisions\/1648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1647"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}