{"id":1653,"date":"2026-03-05T22:07:11","date_gmt":"2026-03-06T05:07:11","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1653"},"modified":"2026-03-05T22:07:42","modified_gmt":"2026-03-06T05:07:42","slug":"tribunal-estatal-electoral-comprometido-con-la-seguridad-de-las-mujeres-sistema-salva","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/05\/tribunal-estatal-electoral-comprometido-con-la-seguridad-de-las-mujeres-sistema-salva\/","title":{"rendered":"Tribunal Estatal Electoral, comprometido con la seguridad de las mujeres: Sistema SALVA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 5 de marzo de 2026.- Como una instituci\u00f3n comprometida con la seguridad de las mujeres en Sonora, reconoci\u00f3 el Sistema de Atenci\u00f3n a la Violencia Familiar y de G\u00e9nero (SALVA) al Tribunal Estatal Electoral (TEE) por su aportaci\u00f3n y compromiso adquirido como una Zona SALVA.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Al contar con la totalidad de su personal capacitado en el protocolo para brindar resguardo a mujeres en riesgo o peligro que soliciten ayuda en sus instalaciones, es ejemplo fiel de la responsabilidad social de coadyuvar con el trabajo que realiza la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) de Sonora para prevenir la violencia hacia las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zulema Boneo Silva, coordinadora estatal de SALVA inform\u00f3 que, el Tribunal se incorpor\u00f3 a la iniciativa del Gobernador Alfonso Durazo en beneficio de las mujeres, formando parte de esta red que ya superan las tres mil Zonas SALVA con presencia en los 72 municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que ser una Zona SALVA implica brindar un apoyo a la ciudadan\u00eda, incluyendo a las mujeres que laboran en la instancia judicial electoral, sus respectivas familias y quienes residen o transitan por el sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 la voluntad y compromiso de la Magistrada Alejandra Velarde F\u00e9lix, presidenta del Tribunal por sumar las instalaciones del recinto como un lugar seguro para las sonorenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambas funcionarias develaron la placa que distingue el inmueble como una Zona SALVA, ubicada en la calle Carlos Ortiz n\u00famero 35 esquina con Avenida Veracruz de la colonia Country Club en Hermosillo.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"1656\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-1656\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.51-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"758\" data-id=\"1655\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-1024x758.jpeg\" alt=\"\" class=\"wp-image-1655\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-1024x758.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-300x222.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-768x569.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-1536x1138.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM-540x400.jpeg 540w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-05-at-8.51.52-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 5 de marzo de 2026.- Como una instituci\u00f3n comprometida con la seguridad de las mujeres en Sonora, reconoci\u00f3 el Sistema de Atenci\u00f3n a la Violencia Familiar y de G\u00e9nero (SALVA) al Tribunal Estatal Electoral (TEE) por su aportaci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-1653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1653"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1653\/revisions"}],"predecessor-version":[{"id":1657,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1653\/revisions\/1657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1654"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}