{"id":1658,"date":"2026-03-05T22:11:56","date_gmt":"2026-03-06T05:11:56","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1658"},"modified":"2026-03-05T22:12:27","modified_gmt":"2026-03-06T05:12:27","slug":"iris-sanchez-chiu-llama-a-convertir-la-igualdad-en-hechos-y-no-solo-en-discursos","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/05\/iris-sanchez-chiu-llama-a-convertir-la-igualdad-en-hechos-y-no-solo-en-discursos\/","title":{"rendered":"Iris S\u00e1nchez Chiu llama a convertir la igualdad en hechos y no s\u00f3lo en discursos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora. Marzo 5 del 2026. En el marco del D\u00eda Internacional de la Mujer, la diputada Iris Fernanda S\u00e1nchez Chiu, coordinadora de la bancada del PRI en el Congreso del Estado de Sonora, se\u00f1al\u00f3 que el 8 de marzo no debe verse como una fecha de celebraci\u00f3n, sino como un momento de reflexi\u00f3n sobre las condiciones de seguridad, igualdad y justicia que enfrentan las mujeres en M\u00e9xico.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Durante su posicionamiento, la legisladora destac\u00f3 que a\u00fan persisten profundas desigualdades y problem\u00e1ticas que afectan a las mujeres, como la violencia de g\u00e9nero, la desaparici\u00f3n de mujeres y la brecha salarial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMientras hablamos aqu\u00ed, 10 mujeres son asesinadas todos los d\u00edas en nuestro pa\u00eds y otras 10 desaparecen diariamente. Adem\u00e1s, siete de cada diez mexicanas han vivido alg\u00fan tipo de violencia\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e1nchez Chiu subray\u00f3 que las mujeres representan m\u00e1s de la mitad de la poblaci\u00f3n del pa\u00eds, pero contin\u00faan enfrentando desigualdades en oportunidades laborales, acceso a la justicia y condiciones de desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su participaci\u00f3n, tambi\u00e9n hizo referencia a tres sectores clave de mujeres en Sonora: la mujer rural, la mujer campesina y la mujer minera, quienes (dijo) sostienen gran parte de la actividad econ\u00f3mica del estado, pero enfrentan m\u00faltiples desaf\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que Sonora es l\u00edder nacional en miner\u00eda, sin embargo, alrededor del 15% de los empleos en ese sector son ocupados por mujeres, lo que evidencia la falta de igualdad en las oportunidades laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora priista enfatiz\u00f3 que la igualdad de g\u00e9nero no puede quedarse \u00fanicamente en discursos o reformas anunciadas, sino que debe traducirse en pol\u00edticas p\u00fablicas reales que garanticen seguridad, igualdad salarial, acceso a oportunidades y justicia con perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mujeres no estamos pidiendo privilegios, estamos exigiendo lo que nos corresponde: respeto, seguridad, justicia y oportunidades\u201d, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la diputada afirm\u00f3 que cuando una mujer avanza, tambi\u00e9n lo hacen su familia, su comunidad y el pa\u00eds, por lo que insisti\u00f3 en la necesidad de construir una sociedad donde hombres y mujeres caminen \u201ccodo a codo, de igual a igual\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 560 \/ 480;\" width=\"560\" controls src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Video-2026-03-05-at-8.53.36-PM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora. Marzo 5 del 2026. En el marco del D\u00eda Internacional de la Mujer, la diputada Iris Fernanda S\u00e1nchez Chiu, coordinadora de la bancada del PRI en el Congreso del Estado de Sonora, se\u00f1al\u00f3 que el 8 de marzo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-1658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1658"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1658\/revisions"}],"predecessor-version":[{"id":1661,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1658\/revisions\/1661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1659"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}