{"id":1752,"date":"2026-03-07T12:01:17","date_gmt":"2026-03-07T19:01:17","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=1752"},"modified":"2026-03-09T12:21:15","modified_gmt":"2026-03-09T19:21:15","slug":"con-medalla-de-bronce-estudiantes-de-cecyte-destacan-en-el-concurso-infomatrix-sudamerica-ecuador-2026-sec","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/07\/con-medalla-de-bronce-estudiantes-de-cecyte-destacan-en-el-concurso-infomatrix-sudamerica-ecuador-2026-sec\/","title":{"rendered":"Con medalla de bronce estudiantes de Cecyte destacan en el concurso Infomatrix Sudam\u00e9rica Ecuador 2026: SEC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 7 de marzo de 2026.- Samantha Arreola Torres y Sergio Felipe Lagunas Coria, estudiantes del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Sonora (Cecyte), plantel Esqueda, ganaron medalla de bronce en el concurso Infomatrix Sudam\u00e9rica Ecuador 2026, destac\u00f3 el titular de la Secretar\u00eda de Educaci\u00f3n y Cultura (SEC).<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Froyl\u00e1n G\u00e1mez Gamboa inform\u00f3 que los j\u00f3venes sonorenses viajaron a Quito, Ecuador, donde representaron a Sonora y M\u00e9xico con el proyecto \u201cAstrobot\u201d, en la categor\u00eda de Divulgaci\u00f3n Cient\u00edfica, en la XX edici\u00f3n del Concurso Iberoamericano de Proyectos Estudiantiles de Ciencia y Tecnolog\u00eda, el cual reuni\u00f3 del 4 al 7 de marzo a j\u00f3venes de diversos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario estatal felicit\u00f3 a los estudiantes por ser motivo de orgullo para las juventudes, as\u00ed como un ejemplo de constancia y dedicaci\u00f3n al superar con \u00e9xito las diversas etapas de selecci\u00f3n del evento organizado por la Sociedad Latinoamericana de Ciencia y Tecnolog\u00eda (Solacyt).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, reafirm\u00f3 el compromiso del gobernador Alfonso Durazo con la educaci\u00f3n de calidad, el impulso al talento joven y el fortalecimiento de la ciencia y la tecnolog\u00eda como \u00e1reas fundamentales para el crecimiento sostenible de Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la directora general de Cecyte Sonora, Blanca Aurelia Valenzuela, destac\u00f3 que Samantha y Sergio Felipe trabajaron arduamente en su proceso de investigaci\u00f3n y preparaci\u00f3n con este proyecto, dise\u00f1ado para explorar el entorno espacial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAstrobot\u201d es una propuesta que consiste en recolectar muestras del entorno espacial para evaluarlas en la b\u00fasqueda de metales, principalmente cobre y titanio. Posteriormente, se analizan estos materiales con el objetivo de fabricar semiconductores m\u00e1s resistentes y eficientes, tanto para su uso espacial como terrestre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo fue desarrollado con la asesor\u00eda de la docente Daniela Ortega Cota, quien ha acompa\u00f1ado a los estudiantes en competencias de Infomatrix y la Feria Mexicana de Ciencias e Ingenier\u00edas (Femeci), tanto en la etapa estatal como nacional, donde han obtenido medallas de plata y bronce con proyectos de gran relevancia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"1758\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-1758\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3-1024x768.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3-300x225.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3-768x576.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3-1536x1152.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-3.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"1757\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2-1024x771.jpeg\" alt=\"\" class=\"wp-image-1757\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2-1024x771.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2-300x226.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2-768x578.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2-1536x1156.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-2.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"1756\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1-1024x771.jpeg\" alt=\"\" class=\"wp-image-1756\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1-1024x771.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1-300x226.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1-768x578.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1-1536x1156.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" data-id=\"1755\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-771x1024.jpeg\" alt=\"\" class=\"wp-image-1755\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-771x1024.jpeg 771w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-226x300.jpeg 226w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-768x1021.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM-1156x1536.jpeg 1156w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.07-PM.jpeg 1204w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"1753\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM-1024x771.jpeg\" alt=\"\" class=\"wp-image-1753\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM-1024x771.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM-300x226.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM-768x578.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM-1536x1156.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-07-at-9.45.06-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 7 de marzo de 2026.- Samantha Arreola Torres y Sergio Felipe Lagunas Coria, estudiantes del Colegio de Estudios Cient\u00edficos y Tecnol\u00f3gicos del Estado de Sonora (Cecyte), plantel Esqueda, ganaron medalla de bronce en el concurso Infomatrix Sudam\u00e9rica Ecuador&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-1752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1752"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1752\/revisions"}],"predecessor-version":[{"id":1759,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/1752\/revisions\/1759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1754"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}