{"id":2191,"date":"2026-03-16T19:44:11","date_gmt":"2026-03-17T02:44:11","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2191"},"modified":"2026-03-16T19:44:17","modified_gmt":"2026-03-17T02:44:17","slug":"neurocirujanos-del-cmn-20-de-noviembre-del-issste-recuperan-movilidad-de-derechohabiente-con-vertebroplastia","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/16\/neurocirujanos-del-cmn-20-de-noviembre-del-issste-recuperan-movilidad-de-derechohabiente-con-vertebroplastia\/","title":{"rendered":"Neurocirujanos del CMN \u201c20 de Noviembre\u201d del ISSSTE recuperan movilidad de derechohabiente con vertebroplastia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u25cf El profesor titular del Curso de Neurocirug\u00eda de Columna Vertebral de Alta Especialidad en el Centro M\u00e9dico Nacional \u201c20 de Noviembre\u201d se\u00f1al\u00f3 que la paciente adulta mayor fue intervenida con este procedimiento de m\u00ednima invasi\u00f3n el 24 de febrero y dos d\u00edas despu\u00e9s fue dada de alta con una notable mejor\u00eda en la recuperaci\u00f3n de sus capacidades f\u00edsicas<br>\u25cf \u201cMe siento feliz de ver a mi mam\u00e1 que nuevamente est\u00e1 caminando, se siente bonito. Mi agradecimiento al Instituto y a los m\u00e9dicos, el doctor Gil, el doctor Chavarr\u00eda, al personal de enfermer\u00eda y a todo el equipo de Neurocirug\u00eda\u201d, comparti\u00f3 la familiar de la paciente<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico, a 16 de marzo de 2026.- Un equipo de especialistas del servicio de Neurocirug\u00eda del Centro M\u00e9dico Nacional (CMN) \u201c20 de Noviembre\u201d, perteneciente al Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), a cargo del director general Mart\u00ed Batres Guadarrama, realiz\u00f3 un procedimiento de m\u00ednima invasi\u00f3n llamado vertebroplastia para reducir el dolor y mejorar la movilidad de una derechohabiente de 73 a\u00f1os con un cuadro grave de osteoporosis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El profesor titular del Curso de Neurocirug\u00eda de Columna Vertebral de Alta Especialidad en este hospital, Cuauht\u00e9moc Gil Ortiz Mej\u00eda, explic\u00f3 que la derechohabiente Honoria Gonz\u00e1lez Galicia acudi\u00f3 a la unidad con dolor severo en cuatro zonas de la columna vertebral, que le imped\u00eda caminar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe realiz\u00f3 un procedimiento de m\u00ednima invasi\u00f3n llamado vertebroplastia, en el cual se colocaron agujas a trav\u00e9s de un aparato de rayos X llamado fluoroscopio, con el que se le insert\u00f3 una resina especial conocido como cemento \u00f3seo quir\u00fargico, en las v\u00e9rtebras L3, L2, L1 y tor\u00e1cica 12. (\u2026) Hoy en d\u00eda tiene el cemento puesto, que le ayuda a contener la fractura y poder realizar su vida normal\u201d, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ortiz Mej\u00eda se\u00f1al\u00f3 que la paciente adulta mayor fue intervenida el 24 de febrero y dos d\u00edas despu\u00e9s fue dada de alta, con una notable mejor\u00eda en la recuperaci\u00f3n de sus capacidades f\u00edsicas, por lo que, subray\u00f3, estos tratamientos de m\u00ednima invasi\u00f3n ofrecen importantes beneficios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUna cirug\u00eda de m\u00ednima invasi\u00f3n tiene muchos beneficios porque el paciente acorta su estancia hospitalaria y acorta los riesgos quir\u00fargicos. (\u2026) La paciente Honoria es un ejemplo m\u00e1s de que seguimos a la vanguardia\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Gonz\u00e1lez Galicia, quien se jubil\u00f3 hace cuatro a\u00f1os, afirm\u00f3 que tras la intervenci\u00f3n recuper\u00f3 la capacidad de caminar y fue dada de alta con cuidados postoperatorios b\u00e1sicos, para continuar con este proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa atenci\u00f3n fue muy buena y los m\u00e9dicos tambi\u00e9n me atendieron muy bien. (\u2026) Ya puedo caminar un poquito m\u00e1s y espero recuperarme m\u00e1s r\u00e1pido para seguir la vida\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la familiar de la paciente, Janet de los Santos Gonz\u00e1lez, agradeci\u00f3 al personal m\u00e9dico el trato profesional que le brind\u00f3 a su madre otra oportunidad de continuar con su vida normal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe siento feliz de ver a mi mam\u00e1 que nuevamente est\u00e1 caminando, se siente bonito. Mi agradecimiento al Instituto y a los m\u00e9dicos, el doctor Gil, el doctor Chavarr\u00eda, al personal de enfermer\u00eda y a todo el equipo de Neurocirug\u00eda\u201d, comparti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Segundo Piso de la Cuarta Transformaci\u00f3n, que encabeza la Presidenta Claudia Sheinbaum Pardo, el ISSSTE refrenda el compromiso con la salud y el bienestar de la poblaci\u00f3n derechohabiente.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2194\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.03-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-2194\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.03-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.03-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.03-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.03-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"663\" data-id=\"2193\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-1-1-1024x663.jpeg\" alt=\"\" class=\"wp-image-2193\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-1-1-1024x663.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-1-1-300x194.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-1-1-768x497.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-1-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"2192\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-2-1024x684.jpeg\" alt=\"\" class=\"wp-image-2192\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-2-1024x684.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-2-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-2-768x513.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-16-at-5.02.02-PM-2.jpeg 1183w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u25cf El profesor titular del Curso de Neurocirug\u00eda de Columna Vertebral de Alta Especialidad en el Centro M\u00e9dico Nacional \u201c20 de Noviembre\u201d se\u00f1al\u00f3 que la paciente adulta mayor fue intervenida con este procedimiento de m\u00ednima invasi\u00f3n el 24 de febrero&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[89,30,88],"tags":[],"class_list":["post-2191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mexico","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2191"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2191\/revisions"}],"predecessor-version":[{"id":2196,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2191\/revisions\/2196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2195"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}