{"id":2219,"date":"2026-03-17T19:21:40","date_gmt":"2026-03-18T02:21:40","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2219"},"modified":"2026-03-19T19:37:03","modified_gmt":"2026-03-20T02:37:03","slug":"resumen-de-la-sesion-ordinaria-del-congreso-de-sonora-martes-17-de-marzo-de-2026","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/17\/resumen-de-la-sesion-ordinaria-del-congreso-de-sonora-martes-17-de-marzo-de-2026\/","title":{"rendered":"Resumen de la sesi\u00f3n ordinaria del Congreso de Sonora, martes 17 de marzo de 2026."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">1 Proyecto de Ley para el Reconocimiento y Fomento de las Organizaciones Estudiantiles del Estado de Sonora.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentado por el diputado Juan Pablo Arenivar Mart\u00ednez, del Partido Acci\u00f3n Nacional.<\/li>\n<\/ul>\n\n\n\n<!--more-->\n\n\n\n<ul class=\"wp-block-list\">\n<li>La propuesta busca establecer un marco jur\u00eddico que reconozca y fortalezca a las organizaciones estudiantiles dentro de las instituciones de educaci\u00f3n superior, garantizando el derecho de las y los estudiantes a organizarse y participar en la vida universitaria.<\/li>\n\n\n\n<li>Asimismo, busca impulsar mecanismos de apoyo para el desarrollo de actividades estudiantiles, asegurar espacios dentro de las universidades para su funcionamiento y promover la transparencia en el uso de los recursos destinados a estas organizaciones.<\/li>\n\n\n\n<li>Fortalece la gobernanza universitaria, promueve la formaci\u00f3n democr\u00e1tica de los estudiantes y garantiza que la voz del alumnado sea escuchada en las decisiones que afectan su formaci\u00f3n acad\u00e9mica y su vida universitaria.<\/li>\n\n\n\n<li>Contempla medidas para proteger a las y los estudiantes contra posibles represalias acad\u00e9micas derivadas de su participaci\u00f3n estudiantil, as\u00ed como acciones que favorezcan a estudiantes for\u00e1neos y fortalezcan la vinculaci\u00f3n entre las universidades y el sector productivo para facilitar oportunidades de pr\u00e1cticas profesionales y empleo.<\/li>\n\n\n\n<li>Se propone la creaci\u00f3n del Consejo Estatal de Participaci\u00f3n Estudiantil de Educaci\u00f3n Superior como un espacio permanente de di\u00e1logo entre estudiantes, instituciones educativas y autoridades del estado, con el prop\u00f3sito de fortalecer la participaci\u00f3n estudiantil y mejorar la vida universitaria en Sonora.<\/li>\n<\/ul>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Reforma en materia de publicidad de est\u00edmulos fiscales municipales.<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentada por los diputados David Figueroa Ortega (PVEM), Rebeca Silva Gallardo (NAS), Emeterio Ochoa Baz\u00faa (PRI) y Juan Pablo Arenivar Mart\u00ednez<\/li>\n\n\n\n<li>Reforma el art\u00edculo 30 y adiciona una fracci\u00f3n VII al art\u00edculo 6\u00ba y los art\u00edculos 30 BIS, 30 TER y 30 QUATER de la Ley de Hacienda Municipal.<\/li>\n\n\n\n<li>La modificaci\u00f3n tiene el fin de fortalecer la facultad constitucional de los ayuntamientos para determinar su pol\u00edtica fiscal y otorgar est\u00edmulos o beneficios tributarios mediante la incorporaci\u00f3n de reglas m\u00ednimas de transparencia, publicidad y certeza jur\u00eddica que permitan a la ciudadan\u00eda conocer con claridad las condiciones bajo las cuales pueden acceder a dichos beneficios.<\/li>\n\n\n\n<li>Actualmente, no existe una regulaci\u00f3n espec\u00edfica que establezca las bases generales para el otorgamiento de beneficios fiscales, ni hay mecanismos que obliguen a los ayuntamientos a emitir reglas de car\u00e1cter general que definan con claridad las condiciones, requisitos y alcances para acceder a tales beneficios.<\/li>\n\n\n\n<li>Esto genera incertidumbre jur\u00eddica para los contribuyentes, quienes carecen de informaci\u00f3n accesible sobre los apoyos disponibles. Y abre, a su vez, espacios de discrecionalidad que resultan contrarios a los principios de transparencia y rendici\u00f3n de cuentas que deben regir la gesti\u00f3n de los recursos p\u00fablicos.<\/li>\n\n\n\n<li>Vincula pr\u00f3rrogas, parcialidades y dem\u00e1s beneficios fiscales a bases generales previamente emitidas.<\/li>\n\n\n\n<li>Reconoce formalmente la facultad municipal de establecer estos apoyos y regular su ejercicio, as\u00ed como la obligaci\u00f3n de definir en sus bases las contribuciones aplicables, los sectores beneficiados, los porcentajes de descuento, la vigencia y la justificaci\u00f3n social o econ\u00f3mica.<\/li>\n\n\n\n<li>Adem\u00e1s, establece que los est\u00edmulos \u00fanicamente surtir\u00e1n efectos cuando sean publicados tanto en el Bolet\u00edn Oficial del Gobierno del Estado como en los portales electr\u00f3nicos oficiales de cada municipio.<\/li>\n<\/ul>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Reforma en materia de simplificaci\u00f3n y digitalizaci\u00f3n de tr\u00e1mites ambientales.<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentada por el diputado Omar Del Valle Colosio, integrante del Grupo Parlamentario del Partido Verde.<\/li>\n\n\n\n<li>Reforma, adiciona y deroga diversas disposiciones de la Ley del Equilibrio Ecol\u00f3gico y Protecci\u00f3n al Ambiente del Estado de Sonora.<\/li>\n\n\n\n<li>Tiene por objeto modernizar el marco jur\u00eddico estatal en materia ambiental mediante la incorporaci\u00f3n de herramientas<br>digitales que permitan simplificar, agilizar y hacer m\u00e1s accesibles los tr\u00e1mites y<br>procedimientos administrativos ambientales.<\/li>\n\n\n\n<li>Establece mecanismos jur\u00eddicos que permitan la presentaci\u00f3n digital de solicitudes, promociones, avisos, c\u00e9dulas y dem\u00e1s actuaciones relacionadas con los tr\u00e1mites ambientales.<\/li>\n\n\n\n<li>Otorga certeza jur\u00eddica al uso de medios electr\u00f3nicos dentro de los procedimientos administrativos en materia ambiental.<\/li>\n\n\n\n<li>Facilita el seguimiento de los expedientes por parte de los promoventes y de la autoridad.<\/li>\n\n\n\n<li>Reduce cargas materiales y costos asociados al manejo exclusivamente f\u00edsico de expedientes.<\/li>\n\n\n\n<li>Fortalece la eficiencia administrativa de CEDES y, en su caso, de los ayuntamientos competentes.<\/li>\n\n\n\n<li>Modifica la Licencia Ambiental Integral, un procedimiento mediante el cual las personas interesadas deben solicitar permisos, licencias, autorizaciones y dem\u00e1s actos administrativos en materia ambiental ante la autoridad competente.<\/li>\n\n\n\n<li>Entre dichos tr\u00e1mites se encuentran la solicitud de licencia ambiental integral, los permisos para combusti\u00f3n a cielo abierto, la autorizaci\u00f3n para operar centros de verificaci\u00f3n vehicular, el registro como generador de residuos de manejo especial, la aprobaci\u00f3n de planes de manejo integral de residuos de manejo especial, el permiso para la prestaci\u00f3n del servicio de transporte de residuos de manejo especial, as\u00ed como la presentaci\u00f3n y evaluaci\u00f3n de la C\u00e9dula de Operaci\u00f3n Anual.<\/li>\n\n\n\n<li>Bajo el esquema vigente, dichos tr\u00e1mites se realizan primordialmente de forma escrita y presencial, una din\u00e1mica genera cargas administrativas relevantes para los promoventes, quienes deben realizar traslados f\u00edsicos, integrar expedientes impresos y asumir costos asociados a papel, impresi\u00f3n, copias y otros insumos materiales.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>1 Proyecto de Ley para el Reconocimiento y Fomento de las Organizaciones Estudiantiles del Estado de Sonora.<\/p>\n","protected":false},"author":1,"featured_media":2220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2219\/revisions"}],"predecessor-version":[{"id":2221,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2219\/revisions\/2221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2220"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}