{"id":2318,"date":"2026-03-19T22:01:11","date_gmt":"2026-03-20T05:01:11","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2318"},"modified":"2026-03-19T22:01:17","modified_gmt":"2026-03-20T05:01:17","slug":"proponen-reforma-para-garantizar-devolucion-de-cuotas-a-trabajadores-sin-limite-de-tiempo","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/19\/proponen-reforma-para-garantizar-devolucion-de-cuotas-a-trabajadores-sin-limite-de-tiempo\/","title":{"rendered":"Proponen reforma para garantizar devoluci\u00f3n de cuotas a trabajadores sin l\u00edmite de tiempo."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora 19 de marzo de 2025. Con el objetivo de proteger los derechos de las y los trabajadores al servicio del Estado, el diputado Emeterio Ochoa Baz\u00faa y la diputada Iris Fernanda S\u00e1nchez Chiu presentaron una iniciativa de reforma al art\u00edculo 92 de la Ley del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado de Sonora (ISSSTESON).<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta busca establecer que la devoluci\u00f3n de las cuotas aportadas al fondo de pensiones \u2014conocida como indemnizaci\u00f3n global\u2014 sea imprescriptible, es decir, que no pierda vigencia con el paso del tiempo para quienes no hayan alcanzado una pensi\u00f3n o jubilaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, la ley establece un plazo de tres a\u00f1os para reclamar estos recursos; de no hacerlo en ese periodo, las aportaciones pasan a favor del Instituto. Esta situaci\u00f3n, se\u00f1alaron los legisladores, representa una afectaci\u00f3n directa a los trabajadores, quienes pierden recursos que les pertenecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe trata de garantizar justicia para quienes, por distintas circunstancias, no lograron cumplir con los a\u00f1os de servicio requeridos para acceder a una pensi\u00f3n, pero s\u00ed aportaron durante su vida laboral\u201d, destac\u00f3 Ochoa Bazua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa se sustenta en el principio de que la seguridad social es un derecho humano reconocido tanto en la Constituci\u00f3n como en tratados internacionales, por lo que debe privilegiarse la protecci\u00f3n m\u00e1s amplia a las personas trabajadoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta reforma, se busca que las cuotas aportadas al fondo de pensiones puedan ser reclamadas en cualquier momento, evitando que las y los trabajadores pierdan el acceso a un recurso que es resultado de su esfuerzo laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los promoventes reiteraron su compromiso de impulsar acciones legislativas que fortalezcan la seguridad social y garanticen condiciones m\u00e1s justas para las y los sonorenses.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"464\" style=\"aspect-ratio: 816 \/ 464;\" width=\"816\" controls src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Video-2026-03-19-at-8.25.19-PM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora 19 de marzo de 2025. Con el objetivo de proteger los derechos de las y los trabajadores al servicio del Estado, el diputado Emeterio Ochoa Baz\u00faa y la diputada Iris Fernanda S\u00e1nchez Chiu presentaron una iniciativa de reforma&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2318"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2318\/revisions"}],"predecessor-version":[{"id":2321,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2318\/revisions\/2321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2320"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}