{"id":2322,"date":"2026-03-19T22:03:54","date_gmt":"2026-03-20T05:03:54","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2322"},"modified":"2026-03-19T22:04:00","modified_gmt":"2026-03-20T05:04:00","slug":"el-gobierno-de-sonora-fortalece-infraestructura-universitaria-en-san-luis-rio-colorado-con-obra-en-la-ues","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/19\/el-gobierno-de-sonora-fortalece-infraestructura-universitaria-en-san-luis-rio-colorado-con-obra-en-la-ues\/","title":{"rendered":"El Gobierno de Sonora fortalece infraestructura universitaria en San Luis R\u00edo Colorado con obra en la UES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">San Luis R\u00edo Colorado, Sonora; 19 de marzo de 2026.- En seguimiento al compromiso del gobernador Alfonso Durazo Monta\u00f1o de mejorar la infraestructura educativa en el estado, el Gobierno de Sonora, a trav\u00e9s del Consejo Estatal de Concertaci\u00f3n para la Obra P\u00fablica (CECOP), concluy\u00f3 los trabajos de recarpeteo con carpeta asf\u00e1ltica en el estacionamiento de la Universidad Estatal de Sonora (UES), Unidad Acad\u00e9mica San Luis R\u00edo Colorado.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Con una inversi\u00f3n de ocho millones 15 mil 91 pesos, benefici\u00f3 a dos mil 45 personas entre estudiantes, docentes y personal administrativo. Los trabajos incluyeron la colocaci\u00f3n de carpeta asf\u00e1ltica, base hidr\u00e1ulica y riego de liga para mejorar la circulaci\u00f3n vehicular y el acceso al campus. Asimismo, se habilitaron 348 cajones de estacionamiento, de los cuales 10 est\u00e1n destinados a personas con movilidad reducida, adem\u00e1s de la instalaci\u00f3n de topes y se\u00f1alizaci\u00f3n horizontal para ordenar el tr\u00e1nsito dentro del \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El corte de list\u00f3n se realiz\u00f3 por parte del Coordinador General del CECOP, Mtro. Melit\u00f3n Alberto S\u00e1nchez Durazo; el alcalde de San Luis R\u00edo Colorado, C\u00e9sar Iv\u00e1n Sandoval G\u00e1mez; el Delegado de Gobernaci\u00f3n, Ricardo Lugo Moreno y el Director de la Universidad Estatal de Sonora en San Luis R\u00edo Colorado, Ing. Carlos Enrique Ram\u00edrez Escamilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obra registrada con un 100 por ciento de avance f\u00edsico, consolidada como una mejora importante para la infraestructura universitaria del municipio. Con acciones como esta, el gobernador Alfonso Durazo Monta\u00f1o contin\u00faa impulsando obras que fortalecen los espacios educativos y brindan mejores condiciones para la formaci\u00f3n de las y los estudiantes sonorenses.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"2327\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-1024x684.jpeg\" alt=\"\" class=\"wp-image-2327\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-1024x684.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-768x513.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-1536x1025.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2048x1367.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"2325\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-1024x684.jpeg\" alt=\"\" class=\"wp-image-2325\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-1024x684.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-768x513.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-1536x1025.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-2-2048x1367.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2324\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-1024x576.jpeg\" alt=\"\" class=\"wp-image-2324\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-1024x576.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-300x169.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-768x432.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-1536x864.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.20-PM-3-2048x1152.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2323\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-1024x576.jpeg\" alt=\"\" class=\"wp-image-2323\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-1024x576.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-300x169.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-768x432.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-1536x864.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.21-PM-2048x1152.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>San Luis R\u00edo Colorado, Sonora; 19 de marzo de 2026.- En seguimiento al compromiso del gobernador Alfonso Durazo Monta\u00f1o de mejorar la infraestructura educativa en el estado, el Gobierno de Sonora, a trav\u00e9s del Consejo Estatal de Concertaci\u00f3n para la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2322"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2322\/revisions"}],"predecessor-version":[{"id":2328,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2322\/revisions\/2328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2326"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}