{"id":2334,"date":"2026-03-19T22:41:39","date_gmt":"2026-03-20T05:41:39","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2334"},"modified":"2026-03-19T22:41:46","modified_gmt":"2026-03-20T05:41:46","slug":"rompe-record-de-participacion-smart-city-hackathon-con-mas-de-200-jovenes-en-hermosillo","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/19\/rompe-record-de-participacion-smart-city-hackathon-con-mas-de-200-jovenes-en-hermosillo\/","title":{"rendered":"Rompe r\u00e9cord de participaci\u00f3n Smart City Hackathon con m\u00e1s de 200 j\u00f3venes en Hermosillo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Se concentraron en instalaciones del Tec de Monterrey para trabajar en convertir sus ideas en propuestas de soluci\u00f3n a problemas de la comunidad.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora, 19 de marzo, 2026.- Por primera vez, se rompe r\u00e9cord de participaci\u00f3n de 234 estudiantes que respondieron a la convocatoria del Ayuntamiento de Hermosillo a trav\u00e9s de la Agencia Municipal de Desarrollo Econ\u00f3mico (AMDE) para desarrollar sus propuestas en el Smart City Hackathon 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director general de la AMDE, Oscar Gast\u00e9lum Donnadieu, destac\u00f3 que a trav\u00e9s de este concurso han resultado grandes proyectos innovadores que atienden problem\u00e1ticas espec\u00edficas en la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que quienes el a\u00f1o pasado participaron con la idea de crear sem\u00e1foros inteligentes, y obtuvieron el apoyo del Presidente Municipal Antonio Astiazar\u00e1n para desarrollar un prototipo, est\u00e1n por iniciar las pruebas en la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn las 3 categor\u00edas, n\u00famero de universidades, n\u00famero de registros y n\u00famero de equipos, rompimos r\u00e9cord, as\u00ed que en esta tercera edici\u00f3n del Hackathon estamos rompiendo r\u00e9cord aqu\u00ed en el Tec de Monterrey, desearles la mejor de las suertes a los 40 equipos, es una competencia muy intensa en la que pasan a la final 10 equipos de 40, yo les dir\u00eda que le echen todas las ganas a sus esfuerzos\u201d, expres\u00f3 el funcionario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Integrados en 40 equipos, las y los estudiantes provenientes de siete universidades participan en las jornadas de trabajo para desarrollar sus proyectos con rumbo a la final el 24 de marzo pr\u00f3ximo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas y todos los concursantes en el reto de este a\u00f1o cuentan con la asesor\u00eda y acompa\u00f1amiento de 40 profesionistas e investigadores de diversos perfiles acad\u00e9micos y profesionales que se registraron como mentores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La edici\u00f3n 2026 convoca a proponer y desarrollar propuestas de soluci\u00f3n en torno a temas como la reducci\u00f3n de consumo de energ\u00eda el\u00e9ctrica en instalaciones deportivas; reducci\u00f3n de siniestros viales por uso de celulares y otras conductas imprudentes; facilitar que personas oyentes que no dominan lenguaje de se\u00f1as mexicana puedan comunicarse con personas sordas; uso de inteligencia artificial para la atracci\u00f3n de inversiones al municipio, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los competidores de la tercera edici\u00f3n del Smart City Hackathon estudian diversas carreras en instituciones como el Tec Milenio, EBC, Tec de Monterrey, UTH, UNIDEP, UNIL\u00cdDER, UNIKINO Y UNISON.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se seleccionar\u00e1n a 10 equipos finalistas que presentar\u00e1n sus proyectos en el evento magistral a realizarse el 24 de marzo pr\u00f3ximo. Habr\u00e1 un primero, segundo y tercer lugar con premios en efectivo de 50 mil, 10 mil y 5 mil pesos, respectivamente, y un programa de incubaci\u00f3n y tambi\u00e9n se realizar\u00e1 un concurso People Choice Award, cuyo equipo ganador recibir\u00e1 premios en especie.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2339\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-2339\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2338\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-2338\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.23-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2337\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-2337\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2336\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-2336\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-19-at-8.25.24-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/OSCAR-GASTELUM-DIR.-AMDE3ra-EDICION-SMART-CITY-HACKATHON.m4v\"><\/video><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/3ra-EDICION-SMART-CITY-HACKATHON-2026.m4v\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>-Se concentraron en instalaciones del Tec de Monterrey para trabajar en convertir sus ideas en propuestas de soluci\u00f3n a problemas de la comunidad.<\/p>\n","protected":false},"author":1,"featured_media":2335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,30],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":2,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":2376,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions\/2376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}