{"id":2383,"date":"2026-03-20T12:35:48","date_gmt":"2026-03-20T19:35:48","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2383"},"modified":"2026-03-20T12:35:53","modified_gmt":"2026-03-20T19:35:53","slug":"de-la-mayor-importancia-el-acuerdo-cona-las-plataformas-para-proteger-a-las-mujeres","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/20\/de-la-mayor-importancia-el-acuerdo-cona-las-plataformas-para-proteger-a-las-mujeres\/","title":{"rendered":"De la mayor importancia el acuerdo cona las plataformas para proteger a las mujeres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El acuerdo de M\u00e9xico con las plataformas digitales para proteger a las ni\u00f1as, a las j\u00f3venes y a las mujeres en general de la violencia digital es de la mayor importancia.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan lo publicado, las medidas han sido pactadas con las plataformas Meta, Google y TikTok, mismas que incluyen la implementaci\u00f3n de herramientas de control de seguridad y, muy importante, la difusi\u00f3n de campa\u00f1as preventivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de M\u00e9xico, como resultado de mesas de trabajo y negociaci\u00f3n, acord\u00f3 con las plataformas digitales combatir la violencia de g\u00e9nero desde sus redes sociales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de M\u00e9xico de la presidenta, Claudia Sheinbaum Pardo ha firmado el acuerdo con las principales plataformas digitales para velar por la protecci\u00f3n de las mujeres ante la violencia digital a la que se exponen constantemente en la internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las medidas pactadas con Meta, Google y TikTok incluyen la incorporaci\u00f3n de mecanismos preventivos -como la difusi\u00f3n de campa\u00f1as para incentivar denuncias en d\u00edas pactados, generar informaci\u00f3n para sensibilizar y crear mesas de di\u00e1logo-, as\u00ed como rutas para crear pol\u00edticas para atender casos de acoso, retirar contenido violento o \u00edntimo no consentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de las Mujeres, Citlali Hern\u00e1ndez, ha calificado el acuerdo de \u201cpionero\u201d y la presidenta, Claudia Sheinbaum, ha a\u00f1adido que ella podr\u00eda ser la primera mujer en usarlo, tras el caso de acoso que vivi\u00f3 el pasado noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es de lamentarse, el informe de Citlali Hern\u00e1ndez, en el sentido de que la empresa Twitter, ahora X, declin\u00f3 participar en los acuerdos alcanzados con sus compa\u00f1eros de industria. \u201cEllos -los directivos- argumentaron que por no tener una oficina en M\u00e9xico no se presentaron a ninguna de las reuniones, no obstante que es una de las redes donde m\u00e1s vemos expresadas estas violencias\u201d, indic\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propia secretaria tiene un proceso abierto contra el empresario Ricardo Salinas Pliego, quien la se\u00f1al\u00f3 en una publicaci\u00f3n por su imagen f\u00edsica. Hern\u00e1ndez interpuso una denuncia por violencia pol\u00edtica de g\u00e9nero contra el magnate y aunque el Instituto Nacional Electoral, INE, orden\u00f3 a Salinas que borrara decenas de tuits con insultos a la pol\u00edtica, este ha apelado y el proceso sigue atascado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los casos de acoso con cr\u00edticas a la apariencia f\u00edsica o clase social, como el que vivi\u00f3 Hern\u00e1ndez, son uno de los tipos de violencia que viven las mujeres en internet, seg\u00fan el Gobierno. Sin embargo, no es el m\u00e1s com\u00fan. Los m\u00e1s frecuentes son insinuaciones o propuestas sexuales, 29 por ciento, recibir contenido sexual 27,5 o suplantaci\u00f3n de identidad 20,5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero tambi\u00e9n otros actos m\u00e1s violentos como la publicaci\u00f3n de fotos o informaci\u00f3n personal 5,9 por ciento o la venta de im\u00e1genes o videos sexuales 4,4. El Instituto Nacional de Geograf\u00eda y Estad\u00edstica, INEGI, cifr\u00f3 en 18,9 millones de personas las que han sufrido ciberacoso en los \u00faltimos cuatro a\u00f1os, un aumento de 4,8 millones respecto a 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1ndez ha matizado que las plataformas ya cuentan con sus propios mecanismos para combatir la violencia digital, como la existencia de normas comunitarias para sus usuarios, mecanismos de denuncia, apego a las leyes locales y recursos para el apoyo a las v\u00edctimas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la firma del acuerdo continuar\u00e1n las reuniones en mesas de di\u00e1logo para fortalecer los procesos existentes e implementar otros nuevos, como las campa\u00f1as de informaci\u00f3n y prevenci\u00f3n del Gobierno. \u201cNo es una ley que proh\u00edba, sino una colaboraci\u00f3n voluntaria en la que Secretar\u00eda de las Mujeres trabaja con las plataformas para hacer conciencia, para prevenir y tambi\u00e9n para atender casos de denuncia\u201d, ha indicado la presidenta, Claudia Sheinbaum Pardo. Espero que la plataforma X se sume al acuerdo so pena de la m\u00e1cula que representa su marginaci\u00f3n y de alguna manera ser se\u00f1alada de complicidad con el acoso cibern\u00e9tico a las mujeres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acuerdo de M\u00e9xico con las plataformas digitales para proteger a las ni\u00f1as, a las j\u00f3venes y a las mujeres en general de la violencia digital es de la mayor importancia.<\/p>\n","protected":false},"author":1,"featured_media":1637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[93],"tags":[],"class_list":["post-2383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2383"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2383\/revisions"}],"predecessor-version":[{"id":2384,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2383\/revisions\/2384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1637"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}