{"id":2514,"date":"2026-03-21T13:30:41","date_gmt":"2026-03-21T20:30:41","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2514"},"modified":"2026-03-22T13:41:12","modified_gmt":"2026-03-22T20:41:12","slug":"con-actividades-en-un-pulmon-de-hermosillo-reciben-gobierno-municipal-y-colectivos-ambientalistas-a-la-primavera","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/21\/con-actividades-en-un-pulmon-de-hermosillo-reciben-gobierno-municipal-y-colectivos-ambientalistas-a-la-primavera\/","title":{"rendered":"Con actividades en un pulm\u00f3n de Hermosillo reciben Gobierno Municipal y colectivos ambientalistas a la primavera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Participaron conjuntamente en una jornada de senderismo interpretativo en el cerro Johnson.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"435\" height=\"284\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/Captura-desde-2026-03-22-13-28-40.png\" alt=\"\" class=\"wp-image-2517\" style=\"width:426px;height:auto\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/Captura-desde-2026-03-22-13-28-40.png 435w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/Captura-desde-2026-03-22-13-28-40-300x196.png 300w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">No. 2105\/2026<br>Hermosillo, Sonora; 21 de marzo, 2026.- Convocados por el Instituto Municipal de Ecolog\u00eda y Pol\u00edtica Ambiental de la Agencia Municipal de Energ\u00eda y Cambio Clim\u00e1tico (AMECC), decenas de personas recibieron a la primavera participando en una caminata en el Cerro Johnson, en la que compartieron informaci\u00f3n de los elementos que conforman este ecosistema natural de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos celebrando el inicio de la primavera en esta que es un \u00e1rea natural protegida del Ayuntamiento de Hermosillo desde el a\u00f1o 2009, la idea es que las personas conozcan que existe este pulm\u00f3n verde donde pueden realizar actividades al aire libre como el senderismo\u201d, explic\u00f3 Claudia Falc\u00f3n, directora del Instituto Municipal de Ecolog\u00eda y Pol\u00edtica Ambiental de la AMECC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coment\u00f3 que la AMECC est\u00e1 a cargo de la administraci\u00f3n y preservaci\u00f3n tanto del Cerro Johnson como el Eco Parque, ambas \u00e1reas naturales protegidas del municipio de Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad sabatina inici\u00f3 desde temprana hora con una charla sobre medidas de seguridad durante el recorrido y recomendaciones sobre la observaci\u00f3n respetuosa del entorno sin alterar la din\u00e1mica natural de la zona, as\u00ed como un conteo y presentaci\u00f3n de las y los participantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el recorrido se compartieron detalles sobre la flora y fauna del cerro Johnson, as\u00ed como recomendaciones para disfrute del lugar preservando su equilibrio natural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formaron parte de esta experiencia integrantes de los colectivo Amigos del Cerro Johnson, de la carrera de Ingenier\u00eda Ambiental de la Universidad Estatal de Sonora, el Club de Plantas Nativas, Naturalmente Divertido A.C., Reduce Tu Huella, la Estaci\u00f3n Regional del Noroeste (ERNO) y de la subdirecci\u00f3n de Calidad del Aire y Econom\u00eda Circular de la AMECC; senderistas y vecinos de la zona.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/CLAUDIA-FALCON-DIR.DEL-INST.MUN_.-DE-ECOLOGIAY-POLITICA-AMBIENTAL-H.A.mp4\"><\/video><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1280 \/ 720;\" width=\"1280\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/SENDERISMO-CERRO-JOHNSON.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>-Participaron conjuntamente en una jornada de senderismo interpretativo en el cerro Johnson.<\/p>\n","protected":false},"author":1,"featured_media":2517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,30],"tags":[],"class_list":["post-2514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2514"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2514\/revisions"}],"predecessor-version":[{"id":2518,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2514\/revisions\/2518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2517"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}