{"id":2553,"date":"2026-03-22T19:23:27","date_gmt":"2026-03-23T02:23:27","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2553"},"modified":"2026-03-22T19:25:07","modified_gmt":"2026-03-23T02:25:07","slug":"exhorta-sspc-sonora-al-uso-responsable-del-9-1-1-y-089-en-semana-santa","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/22\/exhorta-sspc-sonora-al-uso-responsable-del-9-1-1-y-089-en-semana-santa\/","title":{"rendered":"Exhorta SSPC Sonora al uso responsable del 9-1-1 y 089 en Semana Santa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 22 de marzo de 2026.- Con motivo del pr\u00f3ximo periodo vacacional de Semana Santa 2026, el Centro de Control, Comando, Comunicaci\u00f3n, C\u00f3mputo, Coordinaci\u00f3n e Inteligencia (C5i) de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) Sonora hizo un llamado a la ciudadan\u00eda a utilizar de manera responsable las l\u00edneas 9-1-1 y 089.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Durante esta temporada, miles de familias se preparan para viajar, descansar y convivir. Ante el incremento en la movilidad, es fundamental mantener libres estas l\u00edneas, ya que una llamada oportuna puede marcar la diferencia entre la vida y la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Karina Lerma Gonz\u00e1lez, directora general del Centro de Atenci\u00f3n de Llamadas de Emergencia del C5i, destac\u00f3 que atender llamadas falsas o de broma al 9-1-1 retrasa la atenci\u00f3n que podr\u00eda destinarse a situaciones reales que requieren atenci\u00f3n inmediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1al\u00f3 que durante estos d\u00edas, el personal del C5i permanecer\u00e1 disponible las 24 horas para brindar apoyo a la poblaci\u00f3n. Record\u00f3 tambi\u00e9n que la l\u00ednea 089 est\u00e1 habilitada para realizar denuncias an\u00f3nimas de manera segura y confidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El exhorto se extiende a madres y padres de familia para que dialoguen con sus hijas e hijos sobre la importancia de evitar llamadas indebidas y hacer conciencia de que el 9-1-1 debe utilizarse exclusivamente en casos de emergencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estas vacaciones, la prevenci\u00f3n tambi\u00e9n es responsabilidad de todos; usar correctamente el 9-1-1 y el 089 es cuidar tu vida, la de tu familia y la de toda la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 22 de marzo de 2026.- Con motivo del pr\u00f3ximo periodo vacacional de Semana Santa 2026, el Centro de Control, Comando, Comunicaci\u00f3n, C\u00f3mputo, Coordinaci\u00f3n e Inteligencia (C5i) de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) Sonora hizo un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2553"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2553\/revisions"}],"predecessor-version":[{"id":2554,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2553\/revisions\/2554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2555"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}