{"id":2619,"date":"2026-03-23T21:55:22","date_gmt":"2026-03-24T04:55:22","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2619"},"modified":"2026-03-23T21:55:27","modified_gmt":"2026-03-24T04:55:27","slug":"supera-gobierno-de-hermosillo-las-50-mil-castraciones-caninas-y-gatunas-en-2026","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/23\/supera-gobierno-de-hermosillo-las-50-mil-castraciones-caninas-y-gatunas-en-2026\/","title":{"rendered":"Supera Gobierno de Hermosillo las 50 mil castraciones caninas y gatunas en 2026"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>En lo que va de la actual administraci\u00f3n<\/li>\n\n\n\n<li>Dichas intervenciones quir\u00fargicas son un importante avance para el control de la sobrepoblaci\u00f3n de animalitos que terminan en desamparo<\/li>\n<\/ul>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-2622\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-1536x1024.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-1-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 23 de marzo, 2026.- \u201cEste mes de marzo hemos llegado a m\u00e1s de 50 mil castraciones de perros y gatos a trav\u00e9s de las jornadas de castraci\u00f3n que se realizan diariamente y gratuitamente, en el municipio de Hermosillo\u201d, inform\u00f3 David Palafox Celaya, director del Instituto Municipal de Protecci\u00f3n y Bienestar Animal (IMPBA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revel\u00f3 el prop\u00f3sito del Gobierno Municipal que encabeza Antonio Astiazar\u00e1n de superar en el 2026 la cifra de intervenciones realizadas en el 2025, para colocar a Hermosillo en el primer lugar de todo el pa\u00eds por lograr la mayor cantidad de castraciones de animales de compa\u00f1\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director del IMPBA confirm\u00f3 que la administraci\u00f3n municipal tiene una firme convicci\u00f3n y compromiso para lograr el control poblacional de animales sin hogar a mediano plazo, a trav\u00e9s de un m\u00e9todo que atiende esta problem\u00e1tica de forma \u00e9tica y compatible con el bienestar animal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que la campa\u00f1a permanente de castraciones gratuitas que opera el IMPBA no solo procura controlar la sobrepoblaci\u00f3n y mejorar la calidad de vida de los perros y gatos intervenidos, sino que se atienden tambi\u00e9n temas de salud p\u00fablica, medio ambiente, seguridad y orden vecinal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reiter\u00f3 la invitaci\u00f3n a las ciudadanas y ciudadanos que tienen a perros y gatos como animales de compa\u00f1\u00eda a que aprovechen las castraciones que el Gobierno ofrece tanto en sus instalaciones como en jornadas en colonias y comunidades rurales del municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director del IMPBA puso a disposici\u00f3n de quienes requieran mayor informaci\u00f3n, o programar una cita para castrar a sus caninos o felinos, el n\u00famero telef\u00f3nico 6624116700.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2621\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-2621\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-1536x1024.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-2-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2620\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-1024x683.jpeg\" alt=\"\" class=\"wp-image-2620\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-1536x1024.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.33.57-PM-3-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,30],"tags":[],"class_list":["post-2619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"predecessor-version":[{"id":2623,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2619\/revisions\/2623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2622"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}