{"id":2703,"date":"2026-03-24T17:14:42","date_gmt":"2026-03-25T00:14:42","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2703"},"modified":"2026-03-24T17:14:49","modified_gmt":"2026-03-25T00:14:49","slug":"refuerza-gobierno-de-sonora-la-proteccion-animal-con-semana-nacional-de-vacunacion-antirrabica","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/24\/refuerza-gobierno-de-sonora-la-proteccion-animal-con-semana-nacional-de-vacunacion-antirrabica\/","title":{"rendered":"Refuerza Gobierno de Sonora la protecci\u00f3n animal con Semana Nacional de Vacunaci\u00f3n Antirr\u00e1bica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 24 de marzo del 2026.\u2013 El Gobierno de Sonora, a trav\u00e9s de la Secretar\u00eda de Salud P\u00fablica (SSP), invita a la poblaci\u00f3n a participar en la Semana Nacional de Vacunaci\u00f3n Antirr\u00e1bica, una estrategia fundamental para proteger la salud de las mascotas y prevenir enfermedades que pueden afectar a las familias.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Durante esta jornada, que se llevar\u00e1 a cabo del martes 24 al s\u00e1bado 28, se instalar\u00e1n m\u00f3dulos de vacunaci\u00f3n gratuitos en distintos puntos del estado, con un horario de atenci\u00f3n de 9:00 de la ma\u00f1ana a 1:00 de la tarde, para facilitar el acceso de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes 24, la jornada se realizar\u00e1 en la intersecci\u00f3n de Benito Ju\u00e1rez y 5 de Mayo, en la Delegaci\u00f3n Municipal de la colonia Centro, del pueblo de Luis B. S\u00e1nchez, en el municipio de San Luis R\u00edo Colorado. Para el mi\u00e9rcoles 25, el m\u00f3dulo estar\u00e1 ubicado en Abelardo L. Rodr\u00edguez y 1ro de junio, en las inmediaciones de la Iglesia Cat\u00f3lica Santa Clara de As\u00eds, en el Golfo de Santa Clara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jueves 26, las actividades continuar\u00e1n en Puerto Pe\u00f1asco, en la colonia Luis Donaldo Colosio, espec\u00edficamente en Parque El Abuelo, ubicado en la intersecci\u00f3n de Adolfo L\u00f3pez Mateos y calle Oriente, mientras que el viernes 27 la jornada se trasladar\u00e1 a Plutarco El\u00edas Calles, en el DIF Municipal de la colonia Centro, en la avenida Altar y Gustavo D\u00edaz Ordaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el s\u00e1bado 28, en San Luis R\u00edo Colorado, el m\u00f3dulo estar\u00e1 disponible en el Parque Recreativo Club de Leones, ubicado en avenida Guerrero y calle 34, siendo este el \u00faltimo d\u00eda de la campa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La SSP record\u00f3 que la vacunaci\u00f3n antirr\u00e1bica es completamente gratuita, segura y salva vidas, por lo que exhort\u00f3 a las y los due\u00f1os de mascotas a llevar a sus perros y gatos, contribuyendo as\u00ed a mantener comunidades saludables y libres de rabia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"715\" height=\"667\" data-id=\"2708\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-5.jpeg\" alt=\"\" class=\"wp-image-2708\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-5.jpeg 715w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-5-300x280.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-5-428x400.jpeg 428w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"678\" data-id=\"2707\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-1-1.jpeg\" alt=\"\" class=\"wp-image-2707\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-1-1.jpeg 714w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-1-1-300x285.jpeg 300w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"749\" data-id=\"2706\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-2.jpeg\" alt=\"\" class=\"wp-image-2706\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-2.jpeg 716w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-2-287x300.jpeg 287w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"713\" height=\"640\" data-id=\"2705\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-3.jpeg\" alt=\"\" class=\"wp-image-2705\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-3.jpeg 713w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-3-300x269.jpeg 300w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"648\" data-id=\"2704\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-4.jpeg\" alt=\"\" class=\"wp-image-2704\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-4.jpeg 718w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-1.46.20-PM-4-300x271.jpeg 300w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 24 de marzo del 2026.\u2013 El Gobierno de Sonora, a trav\u00e9s de la Secretar\u00eda de Salud P\u00fablica (SSP), invita a la poblaci\u00f3n a participar en la Semana Nacional de Vacunaci\u00f3n Antirr\u00e1bica, una estrategia fundamental para proteger la salud&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2703"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2703\/revisions"}],"predecessor-version":[{"id":2709,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2703\/revisions\/2709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2708"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}