{"id":2805,"date":"2026-03-25T11:31:29","date_gmt":"2026-03-25T18:31:29","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2805"},"modified":"2026-03-26T11:43:23","modified_gmt":"2026-03-26T18:43:23","slug":"gobernador-durazo-transforma-mas-de-150-canchas-deportivas-para-familias-sonorenses-paulina-ocana","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/25\/gobernador-durazo-transforma-mas-de-150-canchas-deportivas-para-familias-sonorenses-paulina-ocana\/","title":{"rendered":"Gobernador Durazo transforma m\u00e1s de 150 canchas deportivas para familias sonorenses: Paulina Oca\u00f1a"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 25 de marzo de 2026.\u2013 Con la recuperaci\u00f3n de m\u00e1s de 150 espacios p\u00fablicos, el gobernador Alfonso Durazo transforma colonias con obras que fortalecen la convivencia, impulsan el deporte y devuelven seguridad y oportunidades a las familias.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1024x683.jpeg\" alt=\"\" class=\"wp-image-2809\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Paulina Oca\u00f1a, jefa de la Oficina del Ejecutivo Estatal, destac\u00f3 que estas acciones responden al compromiso del gobernador Alfonso Durazo de gobernar desde el territorio y atender lo que la gente necesita. Durante la entrega de la rehabilitaci\u00f3n del parque en la colonia Nueva Castilla, subray\u00f3 que cada obra es resultado de escuchar y trabajar junto a la comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY es as\u00ed como trabajamos todos los d\u00edas para traerles resultados, que es lo que nos pide nuestro gobernador Alfonso Durazo, y lo hacemos con much\u00edsimo cari\u00f1o, con much\u00edsimas ganas, y sobre todo siempre estando atentos. Entonces, el que el d\u00eda de hoy se vea materializada esta cancha con esta inversi\u00f3n, lo que m\u00e1s rescato es que se pudo dar la uni\u00f3n entre la sociedad civil y el Gobierno del Estado, que ustedes se organizaron y que platicaron con nosotros\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En coordinaci\u00f3n con la presidenta Claudia Sheinbaum y el gobernador Alfonso Durazo se impulsa la rehabilitaci\u00f3n de 157 canchas adicionales en todo el estado, como parte de una estrategia conjunta para fortalecer el tejido social, promover el deporte y generar entornos seguros para la ni\u00f1ez y la juventud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La rehabilitaci\u00f3n del parque de la colonia Nueva Castilla represent\u00f3 una inversi\u00f3n de 2 millones 719 mil 621 pesos, con la renovaci\u00f3n integral de la cancha de f\u00fatbol, instalaci\u00f3n de pasto sint\u00e9tico, porter\u00edas y cerco perimetral, generando un espacio digno para el deporte, la sana convivencia y el desarrollo de ni\u00f1as, ni\u00f1os y j\u00f3venes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se incorporaron juegos infantiles, ejercitadores, bancas y equipamiento urbano que fortalecen la integraci\u00f3n social y promueven estilos de vida saludables. Esta intervenci\u00f3n beneficia directamente a m\u00e1s de 2 mil 500 habitantes, quienes hoy cuentan con un entorno m\u00e1s seguro y funcional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas obras forman parte de una estrategia estatal para recuperar espacios p\u00fablicos como centros de comunidad y bienestar, consolidando colonias m\u00e1s unidas y con mejores condiciones para el desarrollo social, en l\u00ednea con los principios de la Cuarta Transformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con resultados visibles y acciones concretas, el Gobierno de Sonora avanza en la construcci\u00f3n de un estado m\u00e1s justo, cercano y con bienestar duradero para todas y todos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2808\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-2808\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1-768x511.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.03-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2807\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-2807\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-768x511.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"2806\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-2806\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1-768x511.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-8.52.04-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 25 de marzo de 2026.\u2013 Con la recuperaci\u00f3n de m\u00e1s de 150 espacios p\u00fablicos, el gobernador Alfonso Durazo transforma colonias con obras que fortalecen la convivencia, impulsan el deporte y devuelven seguridad y oportunidades a las familias.<\/p>\n","protected":false},"author":1,"featured_media":2809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[95,30,88],"tags":[],"class_list":["post-2805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gob","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2805"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2805\/revisions"}],"predecessor-version":[{"id":2810,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2805\/revisions\/2810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2809"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}