{"id":2835,"date":"2026-03-25T11:40:14","date_gmt":"2026-03-25T18:40:14","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2835"},"modified":"2026-03-26T11:44:31","modified_gmt":"2026-03-26T18:44:31","slug":"es-momento-de-dignificar-a-nuestros-bomberos-vicky-espinoza","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/25\/es-momento-de-dignificar-a-nuestros-bomberos-vicky-espinoza\/","title":{"rendered":"\u201cEs momento de dignificar a nuestros bomberos\u201d: Vicky Espinoza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">-Diputada se pronuncia a favor de la creaci\u00f3n de una Coordinaci\u00f3n Estatal de Bomberos<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-2836\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-25-at-9.04.56-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 25 de marzo de 2026.\u2013 La diputada Mar\u00eda Eduwiges \u201cVicky\u201d Espinoza Tapia expres\u00f3 su respaldo a la posible creaci\u00f3n de una Coordinaci\u00f3n Estatal de Bomberos, al se\u00f1alar que esta medida no solo permitir\u00e1 mejorar la atenci\u00f3n de emergencias, sino tambi\u00e9n reconocer y dignificar el esfuerzo de mujeres y hombres que, con valent\u00eda y compromiso, arriesgan su vida todos los d\u00edas para proteger a las familias sonorenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n, la legisladora expuso que solo 39 de los 72 municipios del estado cuentan actualmente con cuerpos de bomberos, los cuales, en su mayor\u00eda, operan mediante esquemas de voluntariado o con recursos insuficientes, lo que evidencia la necesidad de una instancia estatal que fortalezca su operaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, destac\u00f3 que, de los mil 649 bomberos registrados en la entidad, \u00fanicamente el 57 por ciento percibe una remuneraci\u00f3n econ\u00f3mica, lo que refleja la situaci\u00f3n de vulnerabilidad laboral en la que se encuentran, a pesar de desempe\u00f1ar una labor fundamental para la seguridad de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espinoza Tapia se\u00f1al\u00f3 que en Sonora existe una deuda hist\u00f3rica con las y los bomberos, ya que no cuentan con un reconocimiento pleno dentro del marco jur\u00eddico estatal, lo que limita su acceso a derechos laborales y a mecanismos de protecci\u00f3n para ellos y sus familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, afirm\u00f3 que esta coordinaci\u00f3n permitir\u00eda un modelo m\u00e1s eficiente, con mejor capacitaci\u00f3n, recursos y coordinaci\u00f3n regional para atender emergencias; adem\u00e1s, subray\u00f3 que debe respetar la autonom\u00eda de los cuerpos locales y funcionar como apoyo, no como sustituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un buen momento para considerar pertinente la creaci\u00f3n de una Coordinaci\u00f3n Estatal de Bomberos en la nueva Ley de Desarrollo, para mejorar la seguridad ciudadana y la eficiencia operativa en situaciones de emergencia. La propuesta de esta coordinaci\u00f3n es fortalecer la respuesta ante emergencias con un enfoque m\u00e1s t\u00e9cnico y estructurado a nivel estatal, con el beneficio de contar con respuestas m\u00e1s r\u00e1pidas y t\u00e9cnicas estandarizadas, protocolos y coordinaci\u00f3n entre bomberos y entidades relacionadas, reduciendo tiempos de respuesta y garantizando una soluci\u00f3n acertada\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradeci\u00f3 la presencia de las y los representantes de los cuerpos de bomberos de los municipios de Cajeme, Benito Ju\u00e1rez, Caborca, Pitiquito, Guaymas, Hermosillo, San Luis R\u00edo Colorado, Nacozari, Quiriego, Esqueda, Fronteras, Puerto Libertad y San Ignacio R\u00edo Muerto. Asimismo, reconoci\u00f3 al comandante Omar Gustavo Mendoza Sa\u00f1udo por su labor y por la representaci\u00f3n que ha desempe\u00f1ado en este esfuerzo conjunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Diputada se pronuncia a favor de la creaci\u00f3n de una Coordinaci\u00f3n Estatal de Bomberos<\/p>\n","protected":false},"author":1,"featured_media":2836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-2835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2835"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2835\/revisions"}],"predecessor-version":[{"id":2837,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2835\/revisions\/2837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2836"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}