{"id":2858,"date":"2026-03-26T19:35:09","date_gmt":"2026-03-27T02:35:09","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=2858"},"modified":"2026-03-26T19:35:15","modified_gmt":"2026-03-27T02:35:15","slug":"policias-estatales-y-defensa-aseguran-397-envoltorios-de-narcotico-en-caborca","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/26\/policias-estatales-y-defensa-aseguran-397-envoltorios-de-narcotico-en-caborca\/","title":{"rendered":"Polic\u00edas Estatales y Defensa aseguran 397 envoltorios de narc\u00f3tico en Caborca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Caborca, Sonora; 26 de marzo de 2026.- Con las acciones del trabajo operativo y de seguridad para inhibir la delincuencia en la regi\u00f3n norte de Sonora, la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP), en coordinaci\u00f3n con la Secretar\u00eda de la Defensa Nacional (Defensa), realiz\u00f3 la detenci\u00f3n de una persona en posesi\u00f3n de distintos envoltorios con narc\u00f3tico.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Durante patrullajes de vigilancia desplegados en la colonia Ni\u00f1os H\u00e9roes de Caborca, elementos de la PESP y Defensa detuvieron a Marcelino \u201cN\u201d, de 20 a\u00f1os de edad, al incautarle dinero en efectivo y alrededor de 99 envoltorios con narc\u00f3tico en diferentes presentaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la inspecci\u00f3n correspondiente, le aseguraron los 99 paquetes, de los cuales 65 conten\u00edan sustancia granulada, cinco polvo blanco y 29 hierba verde, adem\u00e1s de billetes en diferentes denominaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la posesi\u00f3n del narc\u00f3tico, Marcelino \u201cN\u201d fue informado sobre los derechos de las personas detenidas y qued\u00f3 a disposici\u00f3n del Ministerio P\u00fablico, donde continuar\u00e1 con los tr\u00e1mites legales correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el mismo municipio, durante los operativos de vigilancia en la colonia Contreras, la Polic\u00eda Estatal y Defensa realizaron el hallazgo de 298 envoltorios con narc\u00f3tico, los cuales fueron asegurados seg\u00fan el protocolo policial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polic\u00eda Estatal de Seguridad P\u00fablica reafirma su compromiso para prevenir y combatir el delito en acciones coordinadas con los tres niveles de gobierno; adem\u00e1s, reitera el llamado a la ciudadan\u00eda para denunciar este y otros delitos a la l\u00ednea de denuncia an\u00f3nima 089.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota: Las personas detenidas se presumen inocentes y ser\u00e1n tratadas como tales en todas las etapas del procedimiento, mientras no se declare su responsabilidad mediante sentencia emitida por el \u00f3rgano jurisdiccional correspondiente, conforme a lo establecido en el art\u00edculo 13 del C\u00f3digo Nacional de Procedimientos Penales.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"937\" height=\"875\" data-id=\"2860\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.23-PM.jpeg\" alt=\"\" class=\"wp-image-2860\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.23-PM.jpeg 937w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.23-PM-300x280.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.23-PM-768x717.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.23-PM-428x400.jpeg 428w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1001\" data-id=\"2859\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.24-PM-1024x1001.jpeg\" alt=\"\" class=\"wp-image-2859\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.24-PM-1024x1001.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.24-PM-300x293.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.24-PM-768x751.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-26-at-5.39.24-PM.jpeg 1249w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Caborca, Sonora; 26 de marzo de 2026.- Con las acciones del trabajo operativo y de seguridad para inhibir la delincuencia en la regi\u00f3n norte de Sonora, la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP), en coordinaci\u00f3n con la Secretar\u00eda de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,91],"tags":[],"class_list":["post-2858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policiaca"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2858"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2858\/revisions"}],"predecessor-version":[{"id":2861,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/2858\/revisions\/2861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/2860"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}