{"id":3035,"date":"2026-03-31T17:33:43","date_gmt":"2026-04-01T00:33:43","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3035"},"modified":"2026-03-31T17:33:48","modified_gmt":"2026-04-01T00:33:48","slug":"inicia-policia-estatal-de-sonora-proceso-de-evaluacion-en-sitio-para-la-recertificacion-internacional-calea","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/31\/inicia-policia-estatal-de-sonora-proceso-de-evaluacion-en-sitio-para-la-recertificacion-internacional-calea\/","title":{"rendered":"Inicia Polic\u00eda Estatal de Sonora proceso de evaluaci\u00f3n en sitio para la recertificaci\u00f3n internacional CALEA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 31 de marzo de 2026.- Con el objetivo de elevar la calidad del servicio policial y fortalecer la confianza ciudadana, la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) inici\u00f3 formalmente la evaluaci\u00f3n en sitio por parte de la Comisi\u00f3n de Acreditaci\u00f3n para Agencias de Aplicaci\u00f3n de la Ley Inc. (CALEA), por sus siglas en ingl\u00e9s.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-3037\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.50-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Personal especializado del organismo internacional CALEA arrib\u00f3 a la Polic\u00eda Estatal en Sonora para realizar la revisi\u00f3n los d\u00edas 30 y 31 de marzo sobre los est\u00e1ndares vinculados a la funci\u00f3n policial, \u00e1reas administrativas y servicios de apoyo de la Polic\u00eda Estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Jos\u00e9 Guadalupe Mart\u00ednez Lavariega, comisario general de la PESP, recibi\u00f3 al equipo internacional de la CALEA, con quienes sostuvo la primera reuni\u00f3n de trabajo y posteriormente realizaron recorrido por todas las \u00e1reas de la corporaci\u00f3n, donde hicieron entrevistas y se verificaron las funciones de cada departamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mart\u00ednez Lavariega destac\u00f3 que la Polic\u00eda Estatal es una corporaci\u00f3n que ha destacado por ser una de las corporaciones de Sonora certificada desde 2015, como una de las dependencias acreditadas por CALEA, mismo logro que buscan consolidar durante este nuevo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La certificaci\u00f3n CALEA lleva un proceso de evoluci\u00f3n de beneficio para la instituci\u00f3n y la ciudadan\u00eda, que permiten brindar un servicio oportuno a trav\u00e9s de protocolos y directivas estandarizadas, procesos apegados a la ley y con respeto a los derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, la Polic\u00eda Estatal de Seguridad P\u00fablica reafirma su visi\u00f3n de ser una corporaci\u00f3n moderna, confiable y de vanguardia, alineada con las mejores pr\u00e1cticas internacionales en seguridad p\u00fablica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-3038\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-4.32.49-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 848 \/ 480;\" width=\"848\" controls src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/WhatsApp-Video-2026-03-31-at-4.32.55-PM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 31 de marzo de 2026.- Con el objetivo de elevar la calidad del servicio policial y fortalecer la confianza ciudadana, la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP) inici\u00f3 formalmente la evaluaci\u00f3n en sitio por parte de la Comisi\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-3035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3035"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3035\/revisions"}],"predecessor-version":[{"id":3039,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3035\/revisions\/3039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3037"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}