{"id":3046,"date":"2026-03-31T17:38:27","date_gmt":"2026-04-01T00:38:27","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3046"},"modified":"2026-03-31T17:38:32","modified_gmt":"2026-04-01T00:38:32","slug":"de-politica-y-cosas-peores-3","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/03\/31\/de-politica-y-cosas-peores-3\/","title":{"rendered":"DE POL\u00cdTICA Y COSAS PEORES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por las humanidades<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"356\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/caton_.png\" alt=\"\" class=\"wp-image-1634\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/caton_.png 699w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/caton_-300x153.png 300w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Pirulina fue a confesarse con el padre Arsilio. &#8220;Me acuso, padre -le dijo- de tener varios amantes&#8221;. Inquiri\u00f3 el sacerdote: &#8220;\u00bfCu\u00e1ntos?&#8221;. &#8220;Se\u00f1or cura -respondi\u00f3 Pirulina-. El pecado ya se lo dije. Perm\u00edtame reservarme la contabilidad&#8221;\u2026 La maestra le pregunt\u00f3 a Pepito: &#8220;\u00bfQu\u00e9 son los cuadr\u00fapedos?&#8221;. Arriesg\u00f3 el chiquillo: &#8220;\u00bfLos que se emborrachan cuatro veces?&#8221;\u2026 Eran los d\u00edas dif\u00edciles de la Segunda Guerra. Sir Winston Churchill pronunci\u00f3 su c\u00e9lebre discurso despu\u00e9s del ataque de los nazis: &#8220;\u00a1Pelearemos en las playas; pelearemos en el campo, pelearemos en las ciudades\u2026!&#8221;. &#8220;\u00a1Mira! -le dijo lord Feebledick a su mujer, lady Loosebloomers-. \u00a1Igualito que nosotros cuando salimos de vacaciones!&#8221;\u2026 Hecho una furia el pap\u00e1 de la chica fue a hablar con los padres del novio de la muchacha. &#8220;\u00a1Su hijo -les reclam\u00f3 iracundo- embaraz\u00f3 a mi hija!&#8221;. &#8220;\u00a1Ay, qu\u00e9 lindo! -exclam\u00f3 alborozada la mam\u00e1 del galancete-. \u00a1Cuando nazca el beb\u00e9 tr\u00e1iganos un zapatito! \u00a1Nos encanta coleccionar recuerdos de las travesuras que hace Pitorrito!&#8221;\u2026 Se quejaba un se\u00f1or: &#8220;La \u00fanica vez que mi esposa pone atenci\u00f3n a lo que digo es cuando hablo dormido&#8221;\u2026 &#8220;\u00a1Cu\u00e1n sabia es la naturaleza! -dec\u00eda una se\u00f1ora de exuberante regi\u00f3n gl\u00fatea-. \u00a1Cuando llegamos a la edad de estar m\u00e1s tiempo sentadas nos dota de un coj\u00edn m\u00e1s c\u00f3modo!&#8221;\u2026 Me preocupa la desaparici\u00f3n de las humanidades en los programas escolares tanto de la preparatoria como de las universidades e instituciones de educaci\u00f3n superior. De sobra est\u00e1 decir que la ense\u00f1anza de la ciencia y de la t\u00e9cnica es muy importante, pero las disciplinas human\u00edsticas orientan esos conocimientos y les dan sentido. &#8220;El hombre tiene mucho poder, pero no tiene ning\u00fan poder sobre su poder&#8221;. La frase es de Romano Guardini. Otro escritor cat\u00f3lico, Gilbert K. Chesterton, escrib\u00eda con un trasfondo no exento de iron\u00eda amarga: &#8220;La raza humana, a la cual muchos de mis lectores pertenecen\u2026&#8221;. Con eso quer\u00eda decir que a algunos hombres les falta plena humanidad porque carecen de humanismo, es decir de una actitud vital fincada en los valores que definen a lo humano: la verdad, la justicia, la belleza, el bien\u2026 Es importante, entonces, poner al alcance de nuestros j\u00f3venes -de los privilegiados que tienen la oportunidad de estar en una escuela- asignaturas tales como la historia, la literatura, el civismo, la filosof\u00eda, la apreciaci\u00f3n del arte, etc\u00e9tera. Una cultura general es indispensable para cualquier profesionista en el competitivo mundo de hoy. S\u00e9 que la especializaci\u00f3n es necesaria, pero recordemos la ense\u00f1anza de Ortega: &#8220;Si no es un hombre culto, un especialista se vuelve un b\u00e1rbaro que sabe cada vez m\u00e1s acerca de cada vez menos&#8221;. En efecto: el que s\u00f3lo sabe de matem\u00e1ticas -digamos- ni siquiera de matem\u00e1ticas sabe. Lo mismo si s\u00f3lo sabe de derecho, o de ingenier\u00eda, o de contabilidad, o de administraci\u00f3n de negocios, o de lo que sea. Hagamos que las humanidades vuelvan a los programas escolares. Hagamos que nuestros estudiantes se humanicen\u2026 En el elegante restor\u00e1n -&#8220;cocina de autor&#8221; y &#8220;cocina fusi\u00f3n&#8221;- el cliente les dijo a sus compa\u00f1eros de mesa: &#8220;Ah\u00ed viene el mesero trayendo la especialidad de la casa: la cuenta&#8221;\u2026 Un tipo de evidente traza caribe\u00f1a iba por una calle de la Ciudad de M\u00e9xico siguiendo a una guapa chica. Le dec\u00eda una y otra vez: &#8220;\u00a1Me guta ete pa\u00ed!&#8221;. Harta de o\u00edr aquella tarabilla la muchacha se volvi\u00f3 con enojo y le dice: &#8220;\u00a1Est\u00e1 bien! \u00a1Ya me enter\u00e9 de que le gusta este pa\u00eds!&#8221;. &#8220;\u00a1No, chica! -aclara el caribe\u00f1o se\u00f1alando a su cuerpo y apuntando luego al hermoso cuerpo de la joven-. \u00a1Me gusta \u00e9ste para ah\u00ed!&#8221;\u2026 FIN.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por las humanidades<\/p>\n","protected":false},"author":1,"featured_media":1634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[93],"tags":[],"class_list":["post-3046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3046"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3046\/revisions"}],"predecessor-version":[{"id":3047,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3046\/revisions\/3047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1634"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}