{"id":3079,"date":"2026-04-02T21:14:58","date_gmt":"2026-04-03T04:14:58","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3079"},"modified":"2026-04-02T21:15:04","modified_gmt":"2026-04-03T04:15:04","slug":"gobierno-de-sonora-fortalece-infraestructura-ambiental-e-hidrica-en-puerto-penasco","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/04\/02\/gobierno-de-sonora-fortalece-infraestructura-ambiental-e-hidrica-en-puerto-penasco\/","title":{"rendered":"Gobierno de Sonora fortalece infraestructura ambiental e h\u00eddrica en Puerto Pe\u00f1asco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Puerto Pe\u00f1asco, Sonora; 2 de abril de 2026.\u2013 El Gobierno de Sonora busca fortalecer la infraestructura ambiental y garantizar servicios b\u00e1sicos para la poblaci\u00f3n, por lo que el gobernador Alfonso Durazo Monta\u00f1o, a trav\u00e9s de la Secretar\u00eda de Agricultura, Ganader\u00eda, Recursos Hidr\u00e1ulicos, Pesca y Acuacultura (Sagarhpa), impulsa el inicio de obras del relleno sanitario y dos nuevos pozos en Puerto Pe\u00f1asco.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-3080\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de Sonora avanza en este proyecto estrat\u00e9gico que permitir\u00e1 mejorar el manejo de residuos s\u00f3lidos en el municipio, contribuyendo a la protecci\u00f3n del medio ambiente y a la salud p\u00fablica, adem\u00e1s de consolidar condiciones adecuadas para el crecimiento ordenado de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de la Sagarhpa, Celida L\u00f3pez C\u00e1rdenas, acompa\u00f1ada del alcalde Alejandro Verdugo, realiz\u00f3 una gira de trabajo en Puerto Pe\u00f1asco para supervisar el arranque de estas obras, las cuales se desarrollan por instrucci\u00f3n del gobernador Alfonso Durazo, con el compromiso de atender una necesidad prioritaria para las y los habitantes del municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el recorrido, Alejandra Castro Valencia, titular de la Secretar\u00eda de Infraestructura y Desarrollo Urbano (SIDUR), explic\u00f3 que la primera celda del relleno sanitario estar\u00e1 concluida para el mes de diciembre, con capacidad de 170 mil metros c\u00fabicos, en la cual tendr\u00e1 una inversi\u00f3n de 45 millones de pesos, que permitir\u00e1 contar con una infraestructura moderna y funcional para la disposici\u00f3n final de residuos, alineada a criterios ambientales y de sostenibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de esta misma gira, supervisaron tambi\u00e9n la construcci\u00f3n de dos nuevos pozos que realiza la Comisi\u00f3n Estatal del Agua (CEA), con una inversi\u00f3n de 12 millones de pesos, cuyo objetivo es fortalecer el abasto de agua potable en Puerto Pe\u00f1asco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez C\u00e1rdenas detall\u00f3 que estas obras permitir\u00e1n brindar un mejor servicio a la poblaci\u00f3n, incluyendo a habitantes de la zona urbana y ejidatarios, as\u00ed como atender la creciente demanda del sector tur\u00edstico, particularmente en el rubro hotelero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este tipo de proyectos, el Gobierno de Sonora reafirma su compromiso de trabajar de manera coordinada para atender necesidades prioritarias en materia ambiental e h\u00eddrica, consolidando a Puerto Pe\u00f1asco como un destino competitivo y sustentable.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"3084\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-3084\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"3083\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-3083\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.12-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"3082\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.13-PM-1024x683.jpeg\" alt=\"\" class=\"wp-image-3082\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.13-PM-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.13-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.13-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.13-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"3081\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1024x683.jpeg\" alt=\"\" class=\"wp-image-3081\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-02-at-8.43.14-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Pe\u00f1asco, Sonora; 2 de abril de 2026.\u2013 El Gobierno de Sonora busca fortalecer la infraestructura ambiental y garantizar servicios b\u00e1sicos para la poblaci\u00f3n, por lo que el gobernador Alfonso Durazo Monta\u00f1o, a trav\u00e9s de la Secretar\u00eda de Agricultura, Ganader\u00eda,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[95,30,88],"tags":[],"class_list":["post-3079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gob","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3079"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3079\/revisions"}],"predecessor-version":[{"id":3085,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3079\/revisions\/3085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3080"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}