{"id":3216,"date":"2026-04-08T19:43:23","date_gmt":"2026-04-09T02:43:23","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3216"},"modified":"2026-04-08T19:43:29","modified_gmt":"2026-04-09T02:43:29","slug":"no-a-la-pena-de-muerte-para-presos-palestinos-en-israel-mexico-debe-pronunciarse","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/04\/08\/no-a-la-pena-de-muerte-para-presos-palestinos-en-israel-mexico-debe-pronunciarse\/","title":{"rendered":"\u201cNo a la pena de muerte para presos palestinos -en Israel-: M\u00e9xico debe pronunciarse\u201d"},"content":{"rendered":"\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"974\" height=\"469\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/teodoro.png\" alt=\"\" class=\"wp-image-1637\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/teodoro.png 974w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/teodoro-300x144.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/03\/teodoro-768x370.png 768w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El licenciado, diplom\u00e1tico y humanista Luis Garc\u00eda Erdmann, respetado y distinguido colega acad\u00e9mico de n\u00famero de la Academia Nacional de Historia y Geograf\u00eda, ANHG, auspiciada por la Universidad Nacional Aut\u00f3noma de M\u00e9xico, UNAM, est\u00e1 en el impulso de la cruzada cuyo t\u00edtulo lo dice todo: \u201cNO A LA PENA DE MUERTE PARA PRESOS PALESTINOS-EN ISRAEL-: M\u00c9XICO DEBE PRONUNCIARSE\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed la impulsan y la reproducimos \u00edntegra, precisamente por su valor human\u00edstico: \u201cSe acaba de aprobar una ley -en Israel- que permitir\u00eda la pena de muerte para presos palestinos. A\u00fan no se aplica: est\u00e1 siendo impugnada y todav\u00eda se puede frenar. Este es el momento de actuar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la Presidenta de la Rep\u00fablica Mexicana, Claudia Sheinbaum Pardo. A la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. A la Embajada de Israel en M\u00e9xico:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ciudadanas y ciudadanos en M\u00e9xico, expresamos nuestra profunda preocupaci\u00f3n ante la reciente aprobaci\u00f3n de medidas que contemplan la pena de muerte mediante ahorcamiento, que afecta a personas presas palestinas, en un contexto de profunda desigualdad estructural y de aplicaci\u00f3n discriminatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pena capital constituye una violaci\u00f3n grave a los derechos humanos y al derecho internacional. Su posible aplicaci\u00f3n en un contexto de desigualdad estructural y conflicto prolongado agrava su car\u00e1cter injusto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ley, recientemente aprobada por el parlamento israel\u00ed, enfrenta actualmente impugnaciones legales y cuestionamientos internacionales, por lo que a\u00fan existe una posibilidad real de frenar su implementaci\u00f3n. Sin embargo, de no actuar con urgencia, podr\u00eda traducirse en sentencias de muerte y ejecuciones en un corto plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las personas detenidas se encuentran aproximadamente 9,500 presos palestinos, adem\u00e1s de 3,442 personas bajo detenci\u00f3n administrativa (privadas de libertad sin cargos formales ni juicio), as\u00ed como 350 menores de edad y 73 mujeres. La presencia de ni\u00f1as, ni\u00f1os y adolescentes bajo custodia, en condiciones ampliamente cuestionadas por organismos internacionales de derechos humanos, resulta especialmente alarmante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos preocupa la ejecuci\u00f3n y el proceso que la hace posible: la normalizaci\u00f3n de pr\u00e1cticas que deshumanizan y legitiman la violencia extrema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien M\u00e9xico ha sostenido hist\u00f3ricamente una postura en contra de la pena de muerte, consideramos fundamental que, ante esta medida espec\u00edfica, dicha postura se traduzca en acciones y posicionamientos claros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, pedimos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Que el Estado mexicano emita una postura p\u00fablica clara y espec\u00edfica en contra de la aplicaci\u00f3n de la pena de muerte en este caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Que M\u00e9xico impulse acciones concretas en organismos internacionales para frenar su implementaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Que se garantice el respeto al debido proceso y la supervisi\u00f3n internacional de las condiciones de detenci\u00f3n de los presos palestinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico ha sido hist\u00f3ricamente un pa\u00eds que defiende la vida y los derechos humanos. Hoy es fundamental que ese principio se sostenga con claridad y coherencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como sociedad, no podemos permanecer indiferentes ante medidas que legitiman la violencia y la eliminaci\u00f3n de vidas humanas. A\u00fan estamos a tiempo de impedir su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Firma esta petici\u00f3n. Al sumarte a la causa debe ser con Firmas verificadas. Nombre Apellido. Correo electr\u00f3nico. Publicar mi firma y mi comentario sobre esta petici\u00f3n. Al Firma la petici\u00f3n, aceptas las condiciones de servicio y la pol\u00edtica de privacidad de Change.org y tambi\u00e9n aceptas recibir mensajes de correo electr\u00f3nico ocasionalmente sobre campa\u00f1as abiertas en Change.org. Puedes darte de baja en cualquier momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Firma y comparte: https:\/\/www.change.org\/Nopenademuertepresos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Periodista y escritor; presidente del Colegio Nacional de Licenciados en Periodismo, CONALIPE; secretario de Desarrollo Social de la Federaci\u00f3n Latinoamericana de Periodistas, FELAP; presidente fundador y vitalicio honorario de la Federaci\u00f3n de Asociaciones de Periodistas Mexicanos, FAPERMEX, Doctor Honoris Causa por la Universidad Internacional, Acad\u00e9mico de N\u00famero y Director de Comunicaci\u00f3n de la Academia Nacional de Historia y Geograf\u00eda, ANHG. Agradecer\u00e9 sus comentarios y cr\u00edticas en teodororenteriaa@gmail.com Nos escuchamos en las frecuencias en toda la Rep\u00fablica de Libertas Radio. Le invitamos a visitar: www.felap.info, www.ciap-felap.org, www.fapermex.org, y el portal: www.irradianoticias.com<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[93],"tags":[],"class_list":["post-3216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3216"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3216\/revisions"}],"predecessor-version":[{"id":3217,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3216\/revisions\/3217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/1637"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}