{"id":3261,"date":"2026-04-10T10:03:34","date_gmt":"2026-04-10T17:03:34","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3261"},"modified":"2026-04-10T10:03:38","modified_gmt":"2026-04-10T17:03:38","slug":"gobierno-de-sonora-devuelve-el-agua-y-la-esperanza-a-productores-de-ures-con-obras-hidricas-historicas","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/04\/10\/gobierno-de-sonora-devuelve-el-agua-y-la-esperanza-a-productores-de-ures-con-obras-hidricas-historicas\/","title":{"rendered":"Gobierno de Sonora devuelve el agua y la esperanza a productores de Ures con obras h\u00eddricas hist\u00f3ricas"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Ures, Sonora; 9 de abril de 2026.\u2013 Con el prop\u00f3sito de recuperar la productividad del campo y garantizar el acceso al agua, el gobernador Alfonso Durazo Monta\u00f1o, a trav\u00e9s del Gobierno de Sonora, impulsa once obras h\u00eddricas estrat\u00e9gicas en la regi\u00f3n de Ures y El Molino de Camou, en coordinaci\u00f3n con la la secretaria de Agricultura, Ganader\u00eda, Recursos Hidr\u00e1ulicos, Pesca y Acuacultura (Sagarhpa), la Comisi\u00f3n Estatal del Agua (CEA) y la Comisi\u00f3n Nacional del Agua (Conagua).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de este esfuerzo, la Sagarhpa supervis\u00f3 los trabajos en la Unidad de Riego La Granja, en el Ejido San Pedro del municipio de Ures, donde se realiza la perforaci\u00f3n de un pozo profundo de 150 metros, con capacidad de 50 litros por segundo, as\u00ed como la construcci\u00f3n de 1.7 kil\u00f3metros de l\u00ednea de conducci\u00f3n, con una inversi\u00f3n total de 7.5 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones benefician directamente a 32 productores y permiten la recuperaci\u00f3n de 122 hect\u00e1reas que durante a\u00f1os permanecieron sin acceso al agua, lo que hab\u00eda detenido la producci\u00f3n agr\u00edcola y afectado la econom\u00eda de las familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta del Ejido San Pedro, Eduwiges Mart\u00ednez Navarro, expres\u00f3 su agradecimiento al gobernador Alfonso Durazo y a la secretaria Celida L\u00f3pez C\u00e1rdenas, al se\u00f1alar que este pozo representa una respuesta a m\u00e1s de 20 a\u00f1os de solicitudes por parte de la comunidad, luego de que el pozo anterior se abatiera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de Agricultura, Ganader\u00eda, Recursos Hidr\u00e1ulicos, Pesca y Acuacultura, Celida L\u00f3pez C\u00e1rdenas, destac\u00f3 que estas obras forman parte de los once proyectos h\u00eddricos que se desarrollan en la regi\u00f3n de Ures y El Molino de Camou, atendiendo la instrucci\u00f3n del gobernador de fortalecer las unidades de riego.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"3267\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1024x682.jpeg\" alt=\"\" class=\"wp-image-3267\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"3266\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3-682x1024.jpeg\" alt=\"\" class=\"wp-image-3266\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3-682x1024.jpeg 682w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3-200x300.jpeg 200w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3-768x1153.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3-1023x1536.jpeg 1023w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-3.jpeg 1066w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"3265\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2-1024x682.jpeg\" alt=\"\" class=\"wp-image-3265\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-2.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"3264\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-3264\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1-1024x683.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.11.09-AM-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[95,30,88],"tags":[],"class_list":["post-3261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gob","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3261"}],"version-history":[{"count":2,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3261\/revisions"}],"predecessor-version":[{"id":3268,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3261\/revisions\/3268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3264"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}