{"id":3269,"date":"2026-04-10T10:04:37","date_gmt":"2026-04-10T17:04:37","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3269"},"modified":"2026-04-10T10:04:42","modified_gmt":"2026-04-10T17:04:42","slug":"wasapraka-llama-cobardeal-plan-b-por-no-enfrentar-a-la-intervencion-del-narco","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/04\/10\/wasapraka-llama-cobardeal-plan-b-por-no-enfrentar-a-la-intervencion-del-narco\/","title":{"rendered":"WASAPRAKA LLAMA \u201cCOBARDE\u201dAL PLAN B, POR NO ENFRENTAR A LA INTERVENCI\u00d3N DEL NARCO"},"content":{"rendered":"\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM-1024x682.jpeg\" alt=\"\" class=\"wp-image-3270\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM-1024x682.jpeg 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM-300x200.jpeg 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM-768x512.jpeg 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM-1536x1023.jpeg 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-10-at-8.12.45-AM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El diputado sanluisino Juan Pablo Arenivar Mart\u00ednez, integrante del Grupo Parlamentario del Partido Acci\u00f3n Nacional, vot\u00f3 en contra de la minuta federal de reforma electoral, conocida como \u201cPlan B\u201d, al advertir que no solo representa un retroceso para la democracia, sino que evade atender uno de los principales riesgos del proceso electoral en M\u00e9xico: la intervenci\u00f3n del crimen organizado. Se\u00f1al\u00f3 que una reforma de esta magnitud no puede construirse ignorando la realidad que enfrentan diversas regiones del pa\u00eds, donde la violencia incide directamente en la vida democr\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su posicionamiento en tribuna, el legislador calific\u00f3 como \u201ccobarde\u201d la reforma al sostener que evade deliberadamente enfrentar la injerencia del narcotr\u00e1fico en las elecciones. Subray\u00f3 que, en lugar de fortalecer a las instituciones electorales, la minuta las debilita, reduciendo su capacidad de fiscalizaci\u00f3n, supervisi\u00f3n y control, lo que deja en mayor vulnerabilidad tanto a candidatos como a funcionarios electorales y ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arenivar Mart\u00ednez expres\u00f3 su preocupaci\u00f3n por la propuesta de reducir el n\u00famero de regidur\u00edas en los ayuntamientos bajo el argumento de austeridad, al considerar que esta medida parte de una visi\u00f3n centralista que no toma en cuenta la diversidad geogr\u00e1fica, poblacional y social de los municipios de Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, mencion\u00f3 la falta de inclusi\u00f3n de mecanismos que garanticen la participaci\u00f3n juvenil en la toma de decisiones, destacando que, a pesar de que las y los j\u00f3venes representan un sector fundamental de la poblaci\u00f3n, la reforma no contempla acciones afirmativas reales ni figuras como el regidor juvenil. En ese sentido, se\u00f1al\u00f3 que excluir a este sector es negarles su derecho a incidir en la vida p\u00fablica y perpetuar un modelo pol\u00edtico que<br>no responde a las nuevas generaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el diputado subray\u00f3 que la minuta omite atender el problema de fondo relacionado con la intervenci\u00f3n del crimen organizado en los procesos electorales, lo que, dijo, pone en riesgo la integridad de la democracia. Advirti\u00f3 que ignorar esta realidad es permitir que contin\u00fae un contexto en el que la violencia y la intimidaci\u00f3n pueden influir en los resultados electorales, debilitando la confianza ciudadana en las instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador reiter\u00f3 que vot\u00f3 en contra de esta minuta por considerar que no fortalece la democracia, no garantiza mayor representaci\u00f3n ciudadana y, sobre todo, no enfrenta los verdaderos retos del sistema electoral en M\u00e9xico, dejando de lado la seguridad, la inclusi\u00f3n y la legitimidad de los procesos democr\u00e1ticos.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-3269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3269"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3269\/revisions"}],"predecessor-version":[{"id":3271,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3269\/revisions\/3271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3270"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}