{"id":3718,"date":"2026-05-08T22:05:44","date_gmt":"2026-05-09T05:05:44","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3718"},"modified":"2026-05-08T22:05:59","modified_gmt":"2026-05-09T05:05:59","slug":"extirpa-cmn-20-de-noviembre-del-issste-tumor-en-medula-espinal-a-profesor-de-55-anos","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/08\/extirpa-cmn-20-de-noviembre-del-issste-tumor-en-medula-espinal-a-profesor-de-55-anos\/","title":{"rendered":"Extirpa CMN \u201c20 de Noviembre\u201d del ISSSTE tumor en m\u00e9dula espinal a profesor de 55 a\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico, a 8 de mayo de 2026.- El Centro M\u00e9dico Nacional (CMN) \u201c20 de Noviembre\u201d del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), que encabeza el director general Mart\u00ed Batres Guadarrama, practic\u00f3 un procedimiento de extirpaci\u00f3n de m\u00ednima invasi\u00f3n, conocido como resecci\u00f3n de schwannoma lumbar, a fin de retirar un tumor en la m\u00e9dula espinal a un profesor de 55 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cirug\u00eda se llev\u00f3 a cabo el pasado 22 de abril, tras una serie de estudios m\u00e9dicos, mediante los cuales un equipo de especialistas en neurocirug\u00eda, a cargo del doctor Cuauht\u00e9moc Gil Ortiz, detect\u00f3 la masa anormal en el derechohabiente, que le provocaba dolores intensos, sensaci\u00f3n de descargas el\u00e9ctricas y adormecimiento en las piernas, as\u00ed como desvanecimientos repentinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25cf Un equipo de especialistas en neurocirug\u00eda detect\u00f3 un tumor en la zona lumbar de la m\u00e9dula espinal del paciente, lo que le provocaba dolores intensos, sensaci\u00f3n de descargas el\u00e9ctricas y adormecimiento en las piernas, as\u00ed como desvanecimientos repentinos<br>\u25cf El paciente reconoci\u00f3 al personal que particip\u00f3 en la cirug\u00eda de m\u00ednima invasi\u00f3n que dur\u00f3 seis horas, mediante la cual recuper\u00f3 la salud<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la participaci\u00f3n de neurocirujanos, anestesi\u00f3logos, camilleros, as\u00ed como enfermeras y enfermeros, que brindaron todas las atenciones para garantizar el bienestar del derechohabiente, el procedimiento tuvo una duraci\u00f3n de seis horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos d\u00edas despu\u00e9s de la intervenci\u00f3n, el paciente recuper\u00f3 la capacidad de caminar sin esfuerzos ni dolor y fue dado de alta con cuidados m\u00ednimos postoperatorios, por lo que reconoci\u00f3 los esfuerzos del personal de salud que le brind\u00f3 atenci\u00f3n en el CMN \u201c20 de Noviembre\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81-1024x682.png\" alt=\"\" class=\"wp-image-3720\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-81.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradecido con el gran equipo, dirigido por el destacado neurocirujano Cuauht\u00e9moc Gil Ortiz Mej\u00eda, quien me realiz\u00f3 la delicada y compleja cirug\u00eda para extirpar totalmente un tumor presente en mi m\u00e9dula espinal y zona discal, en la zona lumbar. (\u2026) En suma, mil gracias al personal del Centro M\u00e9dico Nacional \u201820 de Noviembre\u2019 del ISSSTE, que me sigue atendiendo\u201d, comparti\u00f3 en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Segundo Piso de la Cuarta Transformaci\u00f3n, que encabeza la Presidenta Claudia Sheinbaum Pardo, el ISSSTE fortalece la atenci\u00f3n m\u00e9dica de especialidad que brinda a la derechohabiencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;ooo000ooo&#8212;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00edguenos en:<br>X: @ISSSTE_mx<br>Facebook: @ISSSTE_MX<br>Instagram: issste.mx<br>YouTube: ISSSTE_MX<br>Portal electr\u00f3nico: gob.mx\/issste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico, a 8 de mayo de 2026.- El Centro M\u00e9dico Nacional (CMN) \u201c20 de Noviembre\u201d del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), que encabeza el director general Mart\u00ed Batres Guadarrama, practic\u00f3 un&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-3718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3718"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3718\/revisions"}],"predecessor-version":[{"id":3721,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3718\/revisions\/3721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3720"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}