{"id":3727,"date":"2026-05-08T22:08:00","date_gmt":"2026-05-09T05:08:00","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3727"},"modified":"2026-05-08T22:08:13","modified_gmt":"2026-05-09T05:08:13","slug":"promueve-secretaria-de-seguridad-entre-jovenes-de-secundaria-la-importancia-del-bienestar-emocional","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/08\/promueve-secretaria-de-seguridad-entre-jovenes-de-secundaria-la-importancia-del-bienestar-emocional\/","title":{"rendered":"Promueve Secretar\u00eda de Seguridad entre j\u00f3venes de secundaria la importancia del Bienestar Emocional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 8 de mayo de 2026.- Para promover entre j\u00f3venes de secundaria un crecimiento saludable y equilibrado, as\u00ed como impulsar el fortalecimiento de su autoestima, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) en Sonora ofrece pl\u00e1ticas en centros educativos sobre Bienestar Emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del trabajo de prevenci\u00f3n dirigido a la adolescencia y juventud que impulsa la SSPC Sonora, a trav\u00e9s de la estrategia Jornada Permanente por la Paz, se inici\u00f3 con la impartici\u00f3n de la pl\u00e1tica \u201cCambiemos la Narrativa\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-84-1024x768.png\" alt=\"\" class=\"wp-image-3728\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-84-1024x768.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-84-300x225.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-84-768x576.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-84.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Para ello, los equipos del Centro de Prevenci\u00f3n del Delito y Participaci\u00f3n Ciudadana, con el respaldo de la Direcci\u00f3n General de Salud Mental y Adicciones, previamente adquirieron herramientas para transmitir, a su vez, a las y los j\u00f3venes la importancia de trabajar en el bienestar emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una primera etapa, fueron beneficiados con la sesi\u00f3n informativa las y los alumnos de los turnos matutino y vespertino de la Secundaria T\u00e9cnica 6 \u201cManuel Ortiz Paredes\u201d, ubicada en la colonia Coloso Bajo, en Hermosillo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-86-1024x768.png\" alt=\"\" class=\"wp-image-3730\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-86-1024x768.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-86-300x225.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-86-768x576.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-86.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">De entre los temas que se abordaron con la poblaci\u00f3n estudiantil destacan: la prevenci\u00f3n del suicidio, manejo de emociones, toma de decisiones y la construcci\u00f3n de una vida con equilibrio y prop\u00f3sito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ser la atenci\u00f3n de las juventudes uno de los ejes de la Jornada Permanente por la Paz, el Centro de Prevenci\u00f3n del Delito desarrolla actividades con la intenci\u00f3n de reducir riesgos sociales como violencia, adicciones, aislamiento o acoso escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 8 de mayo de 2026.- Para promover entre j\u00f3venes de secundaria un crecimiento saludable y equilibrado, as\u00ed como impulsar el fortalecimiento de su autoestima, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) en Sonora ofrece pl\u00e1ticas en centros&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-3727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3727"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3727\/revisions"}],"predecessor-version":[{"id":3731,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3727\/revisions\/3731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3729"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}