{"id":3747,"date":"2026-05-08T22:14:07","date_gmt":"2026-05-09T05:14:07","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3747"},"modified":"2026-05-08T22:14:35","modified_gmt":"2026-05-09T05:14:35","slug":"el-papa-leon-xiv-honra-a-los-periodistas-asesinados","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/08\/el-papa-leon-xiv-honra-a-los-periodistas-asesinados\/","title":{"rendered":"El papa Le\u00f3n XIV honra a los periodistas asesinados"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"974\" height=\"469\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-96.png\" alt=\"\" class=\"wp-image-3748\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-96.png 974w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-96-300x144.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-96-768x370.png 768w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>LA SANT\u00cdSIMA TRINIDAD, DOLORES HIDALGO, GUANAJUATO; 8 de mayo de 2026.- La oficina de Comunicaci\u00f3n Social de El Vaticano difundi\u00f3 que \u201cel Papa denuncia ataques a la prensa y honra a periodistas asesinados\u201d, declaraci\u00f3n que demuestra que el todav\u00eda flamante sumo pont\u00edfice de la Iglesia Cat\u00f3lica, Apost\u00f3lica y Romana Le\u00f3n XIV, nacido en Estados Unidos, se ha comprometido con los m\u00e1s graves problemas sociales del mundo como es la lucha por aliviar la pobreza, proteger la inmigraci\u00f3n, cancelar las guerras, defender las libertades de prensa e informaci\u00f3n y proteger la integridad f\u00edsica de los periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn el marco de la Jornada Mundial de la Libertad de Prensa, promovida por la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura, UNESCO, el Papa expres\u00f3 su preocupaci\u00f3n por las constantes violaciones a este derecho fundamental, denunciando que en muchos lugares se vulnera de forma evidente o encubierta, y record\u00f3 a los numerosos periodistas y reporteros que han perdido la vida a causa de las guerras y la violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sus saludos despu\u00e9s del Regina Caeli, el Papa Le\u00f3n XIV record\u00f3 a los tantos periodistas asesinados a causa de la violencia. En el marco de la Jornada Mundial de la Libertad de Prensa, patrocinada por la UNESCO, el Papa lament\u00f3 que este derecho fundamental sea vulnerado con frecuencia, a veces de manera evidente y otras de forma silenciosa. Asimismo, record\u00f3 a los numerosos periodistas y reporteros que han perdido la vida a causa de guerras y actos de violencia, destacando su testimonio como un llamado a la verdad y la justicia. El Papa invita a rezar el Rosario por la paz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En nuestro pa\u00eds, con el asesinato del colega, Carlos Castro ocurrido el 8 de enero en Poza Rica, Veracruz, el primero que se registra en el 2026, el resumen del Monitoreo Permanente del Gremio Period\u00edstico organizado de M\u00e9xico es el siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que va de la administraci\u00f3n de la presidenta, Claudia Sheinbaum Pardo, suman 13 cr\u00edmenes mortales, el hallazgo del cuerpo de un colega desaparecido desde 2019 y 2 desapariciones forzadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De 2000 a la fecha, han ocurrido 340 asesinatos: 282 periodistas; 9 locutores; 16 trabajadores de la prensa; 16 familiares y 12 amigos de comunicadores; 2 civiles, y 3 escoltas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En consecuencia, de 1983 a la fecha, de acuerdo con el Monitoreo Permanente de los Asesinatos y Desapariciones Forzadas de Periodistas, suman 406 asesinatos, de los cuales han sido v\u00edctimas: 344 periodistas; 9 locutores; 16 trabajadores de prensa; 19 familiares y 13 amigos de comunicadores; 2 civiles, y 3 escoltas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DESAPARICIONES FORZADAS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Total, de Desapariciones forzadas: 30: 26 periodistas, 3 trabajadores de prensa y 1 amigo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gremio Organizado: Federaci\u00f3n de Asociaciones de Periodistas Mexicanos, FAPERMEX; Federaci\u00f3n Latinoamericana de Periodistas, FELAP-M\u00e9xico, y su brazo acad\u00e9mico, Colegio Nacional de Licenciados en Periodismo, CONALIPE, en sus comunicados correspondientes firmados por sus dirigentes, reitera en forma constante su demanda a las m\u00e1s altas autoridades del pa\u00eds para que terminen con esta vergonzosa impunidad en cuanto a los atentados a los informadores, y cumplan con las medidas cautelares para protegerlos, como lo ordenan las leyes correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro concentrado es terrible y lamentable por todos los conceptos, puesto que la imperante y vergonzosa impunidad es la que permite que los criminales, enemigos de las libertades de prensa y expresi\u00f3n, burlen a la justicia. Como se puede comprobar la lista l\u00fagubre aumenta exponencialmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redoblamos el reclamo de justicia y de que se implementen los mecanismos de protecci\u00f3n a los periodistas, trabajadores de prensa, de sus familiares y amigos que tambi\u00e9n han sido victimados en hechos, inclusive directos, para amedrentar a los comunicadores. \u00a1YA BASTA! Es nuestro grito permanente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n reiteramos el llamado a la presidenta Claudia Sheinbaum Pardo, al Congreso de la Uni\u00f3n, a los gobernadores de las entidades federativas y a los congresos locales, para que atiendan a la brevedad la Agenda Legislativa Pendiente del Periodista, que consideramos es el mayor blindaje para los comunicadores y por su contenido es un instrumento integral para asegurar las libertades de prensa y expresi\u00f3n en nuestro M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inician la lista de dirigentes firmantes, por FAPERMEX: periodista Luis Javier Hern\u00e1ndez C\u00f3rdova, presidente del Consejo Directivo; por CONALIPE: maestro Teodoro Ra\u00fal Renter\u00eda Villa, vicepresidente, y el autor, presidente de CONALIPE, presidente fundador y vitalicio honorario de FAPERMEX y secretario de Desarrollo Social de FELAP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Periodista y escritor; presidente del Colegio Nacional de Licenciados en Periodismo, CONALIPE; secretario de Desarrollo Social de la Federaci\u00f3n Latinoamericana de Periodistas, FELAP; presidente fundador y vitalicio honorario de la Federaci\u00f3n de Asociaciones de Periodistas Mexicanos, FAPERMEX, Doctor Honoris Causa por la Universidad Internacional, Acad\u00e9mico de N\u00famero y director de Comunicaci\u00f3n de la Academia Nacional de Historia y Geograf\u00eda, ANHG. Agradecer\u00e9 sus comentarios y cr\u00edticas en teodororenteriaa@gmail.com Nos escuchamos en las frecuencias en toda la Rep\u00fablica de Libertas Radio. Le invitamos a visitar: www.felap.info, www.ciap-felap.org, www.fapermex.org, y el portal: www.irradianoticias.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA SANT\u00cdSIMA TRINIDAD, DOLORES HIDALGO, GUANAJUATO; 8 de mayo de 2026.- La oficina de Comunicaci\u00f3n Social de El Vaticano difundi\u00f3 que \u201cel Papa denuncia ataques a la prensa y honra a periodistas asesinados\u201d, declaraci\u00f3n que demuestra que el todav\u00eda flamante&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[93],"tags":[],"class_list":["post-3747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3747"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3747\/revisions"}],"predecessor-version":[{"id":3749,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3747\/revisions\/3749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3748"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}