{"id":3819,"date":"2026-05-12T21:12:16","date_gmt":"2026-05-13T04:12:16","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3819"},"modified":"2026-05-12T21:21:16","modified_gmt":"2026-05-13T04:21:16","slug":"inauguran-exposicion-liberatio-trazos-libertarios-como-parte-de-la-ruta-del-arte-de-las-fiestas-del-pitic-2026","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/12\/inauguran-exposicion-liberatio-trazos-libertarios-como-parte-de-la-ruta-del-arte-de-las-fiestas-del-pitic-2026\/","title":{"rendered":"Inauguran exposici\u00f3n Liberatio, Trazos Libertarios como parte de la Ruta del Arte de las Fiestas del Pitic 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Hermosillo, Sonora; 12 de mayo, 2026.-\u00a0Con la inauguraci\u00f3n de la exposici\u00f3n Liberatio, Trazos Libertarios, del artista visual V\u00edctor Haro, inici\u00f3 la Ruta del Arte de las Fiestas del Pitic 2026, que re\u00fane diversas propuestas visuales de artistas sonorenses.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-131-1024x899.png\" alt=\"\" class=\"wp-image-3820\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs muy especial esta noche en la que damos el banderazo a la Ruta del Arte con una presencia importante de las artes visuales, como lo es V\u00edctor Haro en esta gran fiesta cultural que son las Fiestas del Pitic\u201d, expres\u00f3 Marianna Gonz\u00e1lez Gast\u00e9lum, directora del Instituto Municipal de Cultura y Arte (IMCA) al inaugurar la exposici\u00f3n Liberatio, Trazos Libertarios, del artista visual V\u00edctor Haro.<br>Marianna Gonz\u00e1lez encabez\u00f3 la apertura de esta muestra, con la que el autor celebra m\u00e1s de 40 a\u00f1os de trayectoria art\u00edstica, acompa\u00f1ada de Alma Sof\u00eda Garc\u00eda, directora de Quinta de Anza; Roberto Zambrano Loustaunau, socio de Rancho El 17 y Martha Figueroa.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"780\" data-id=\"3821\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132-1024x780.png\" alt=\"\" class=\"wp-image-3821\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132-1024x780.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132-300x229.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132-768x585.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132-110x85.png 110w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-132.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-id=\"3822\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-133-1024x684.png\" alt=\"\" class=\"wp-image-3822\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-133-1024x684.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-133-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-133-768x513.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-133.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El artista visual V\u00edctor Haro comparti\u00f3 su entusiasmo por formar parte de la Ruta del Arte y destac\u00f3 que las Fiestas del Pitic son un festival que enaltece la cultura y las artes.<br>Coment\u00f3 que esta exposici\u00f3n incluye 10 piezas de una muestra m\u00e1s amplia y explic\u00f3 que podr\u00e1 visitarse durante las Fiestas del Pitic y durante el mes de junio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 12 de mayo, 2026.-\u00a0Con la inauguraci\u00f3n de la exposici\u00f3n Liberatio, Trazos Libertarios, del artista visual V\u00edctor Haro, inici\u00f3 la Ruta del Arte de las Fiestas del Pitic 2026, que re\u00fane diversas propuestas visuales de artistas sonorenses. \u201cEs muy&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[86,96,30],"tags":[],"class_list":["post-3819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hermosillo","category-mun","category-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3819"}],"version-history":[{"count":2,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3819\/revisions"}],"predecessor-version":[{"id":3825,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3819\/revisions\/3825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3820"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}