{"id":3855,"date":"2026-05-13T20:44:32","date_gmt":"2026-05-14T03:44:32","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=3855"},"modified":"2026-05-13T20:44:46","modified_gmt":"2026-05-14T03:44:46","slug":"colgar-y-denunciar-la-extorsion-al-089-puede-hacer-la-diferencia","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/13\/colgar-y-denunciar-la-extorsion-al-089-puede-hacer-la-diferencia\/","title":{"rendered":"Colgar y denunciar la extorsi\u00f3n al 089 puede hacer la diferencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 13 de mayo de 2026.- Gracias al uso de la aplicaci\u00f3n 089 Sonora y a la informaci\u00f3n preventiva difundida por la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) Sonora, de enero a mayo de 2026 se logr\u00f3 evitar que mil 152 llamadas de extorsi\u00f3n telef\u00f3nica fueran consumadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e1pida reacci\u00f3n de la ciudadan\u00eda, sumada a las herramientas tecnol\u00f3gicas del C5i Sonora, ha permitido detectar enga\u00f1os, evitar dep\u00f3sitos y proteger el patrimonio de las familias sonorenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se destaca que la app 089 Sonora se ha convertido en una herramienta clave para reportar llamadas sospechosas de manera an\u00f3nima y recibir orientaci\u00f3n inmediata ante posibles casos de extorsi\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-148-819x1024.png\" alt=\"\" class=\"wp-image-3856\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-148-819x1024.png 819w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-148-240x300.png 240w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-148-768x961.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-148.png 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para evitar ser v\u00edctima de este delito, se recomienda mantener la calma durante la llamada, no compartir informaci\u00f3n personal o bancaria, confirmar cualquier situaci\u00f3n con familiares, no realizar dep\u00f3sitos ni transferencias, reportar inmediatamente al 089 y, en caso de no contar con ella, descargar y utilizar correctamente la aplicaci\u00f3n 089 Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La SSPC Sonora reitera el llamado a continuar utilizando las herramientas de prevenci\u00f3n y denunciar cualquier intento de enga\u00f1o telef\u00f3nico, recordando que la informaci\u00f3n y la denuncia oportuna pueden evitar que una llamada termine en delito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 13 de mayo de 2026.- Gracias al uso de la aplicaci\u00f3n 089 Sonora y a la informaci\u00f3n preventiva difundida por la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) Sonora, de enero a mayo de 2026 se logr\u00f3 evitar&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-3855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3855"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3855\/revisions"}],"predecessor-version":[{"id":3857,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/3855\/revisions\/3857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/3856"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}