{"id":4081,"date":"2026-05-22T18:51:09","date_gmt":"2026-05-23T01:51:09","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=4081"},"modified":"2026-05-22T18:51:30","modified_gmt":"2026-05-23T01:51:30","slug":"logra-guardia-nacional-aseguramientos-en-atil","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/22\/logra-guardia-nacional-aseguramientos-en-atil\/","title":{"rendered":"Logra Guardia Nacional aseguramientos en Atil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Personal de la Guardia Nacional, en coordinaci\u00f3n con el Ej\u00e9rcito Mexicano y derivado de informaci\u00f3n de inteligencia militar central, logr\u00f3 dos importantes aseguramientos en las inmediaciones de la comunidad de Atil, como parte de las acciones implementadas para limitar el tr\u00e1fico de drogas, armas y detener a generadores de violencia en el estado de Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante los operativos fueron asegurados m\u00e1s de 102 kgs. de diversas drogas, entre ellas fentanilo en polvo y en pastillas, metanfetamina, goma de opio, hero\u00edna y coca\u00edna, adem\u00e1s de seis armas largas, 30 cargadores, dos chalecos antibalas, dos veh\u00edculos y la detenci\u00f3n de una persona presuntamente vinculada con actividades il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La persona detenida, as\u00ed como los veh\u00edculos, el armamento y la droga asegurada, fueron puestos a disposici\u00f3n de la autoridad competente, con el prop\u00f3sito de continuar con las investigaciones correspondientes y determinar su situaci\u00f3n jur\u00eddica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-278-1024x768.png\" alt=\"\" class=\"wp-image-4083\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-278-1024x768.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-278-300x225.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-278-768x576.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-278.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones representan un golpe significativo a las operaciones del crimen organizado, ya que se estima que la droga asegurada tendr\u00eda un valor superior a los 250 millones de pesos, afectando las finanzas de los grupos delictivos, limitando la compra de armas que utilizan para generar violencia en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Guardia Nacional reitera su compromiso de mantener la coordinaci\u00f3n interinstitucional con autoridades de los tres \u00f3rdenes de gobierno, con el objetivo de disminuir el \u00edndice de homicidios, obtener resultados, detener generadores de violencia, mejorar las condiciones de seguridad y paz de la sociedad sonorense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guardia Nacional \u2013 Justicia y Paz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de la Guardia Nacional, en coordinaci\u00f3n con el Ej\u00e9rcito Mexicano y derivado de informaci\u00f3n de inteligencia militar central, logr\u00f3 dos importantes aseguramientos en las inmediaciones de la comunidad de Atil, como parte de las acciones implementadas para limitar el&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-4081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4081"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4081\/revisions"}],"predecessor-version":[{"id":4084,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4081\/revisions\/4084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/4082"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}