{"id":4101,"date":"2026-05-22T19:08:09","date_gmt":"2026-05-23T02:08:09","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=4101"},"modified":"2026-05-22T19:08:23","modified_gmt":"2026-05-23T02:08:23","slug":"congreso-de-sonora-aprueba-reformas-en-materia-de-austeridad-acceso-a-la-justicia-y-uso-de-la-fuerza-publica","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/05\/22\/congreso-de-sonora-aprueba-reformas-en-materia-de-austeridad-acceso-a-la-justicia-y-uso-de-la-fuerza-publica\/","title":{"rendered":"Congreso de Sonora aprueba reformas en materia de austeridad, acceso a la justicia y uso de la fuerza p\u00fablica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2022 Rinde protesta Eduardo Quiroga Jim\u00e9nez como diputado de la 64 Legislatura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 22 de mayo de 2026.- En sesi\u00f3n extraordinaria, el Congreso del Estado de Sonora aprob\u00f3 diversas reformas e iniciativas en materia de austeridad republicana, acceso a la justicia, protecci\u00f3n de ni\u00f1as, ni\u00f1os y adolescentes, combate a la violencia contra las mujeres y regulaci\u00f3n del uso de la fuerza p\u00fablica. Adem\u00e1s, turn\u00f3 a comisi\u00f3n una iniciativa sobre inclusi\u00f3n y aprob\u00f3 la creaci\u00f3n de una nueva Ley de Mecanismos Alternativos de Soluci\u00f3n de Controversias para el Estado de Sonora. Asimismo, rindi\u00f3 protesta el ciudadano Eduardo Quiroga Jim\u00e9nez como diputado integrante de la 64 Legislatura.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"591\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286-1024x591.png\" alt=\"\" class=\"wp-image-4102\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286-1024x591.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286-300x173.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286-768x444.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286-1536x887.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-286.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el Pleno de esta soberan\u00eda, la diputada Alejandra L\u00f3pez Noriega, presidenta de la Mesa Directiva de la Diputaci\u00f3n Permanente, tom\u00f3 protesta de ley al ciudadano Eduardo Quiroga Jim\u00e9nez (NAS), quien asumi\u00f3 formalmente el cargo de diputado propietario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nombre de la Comisi\u00f3n de R\u00e9gimen Interno y Concertaci\u00f3n Pol\u00edtica (CRICP), la diputada Jazm\u00edn Guadalupe G\u00f3mez Liz\u00e1rraga (PT) dio lectura a la propuesta para modificar la integraci\u00f3n de la Mesa Directiva del Poder Legislativo, derivado de la licencia indefinida solicitada por el diputado Ferm\u00edn Trujillo Fuentes, quien formaba parte de dicho \u00f3rgano. En consecuencia, la diputada Gabriela Tapia Fonllem se integr\u00f3 como suplente en la conformaci\u00f3n de la Mesa Directiva.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287-1024x682.png\" alt=\"\" class=\"wp-image-4103\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-287.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado David Figueroa Ortega y(PVEM) someti\u00f3 a consideraci\u00f3n el dictamen presentado por la Comisi\u00f3n de Gobernaci\u00f3n y Puntos Constitucionales, mediante el cual se armoniza la Constituci\u00f3n del Estado de Sonora con la reforma federal en materia de austeridad republicana. La propuesta contempla l\u00edmites al presupuesto del Congreso local, reducci\u00f3n de regidur\u00edas municipales, regulaci\u00f3n salarial de autoridades electorales y fortalecimiento de los principios de paridad de g\u00e9nero, igualdad sustantiva y perspectiva de g\u00e9nero.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296-1024x771.png\" alt=\"\" class=\"wp-image-4112\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296-1024x771.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296-300x226.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296-768x578.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296-1536x1157.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-296.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enseguida, la diputada Jazm\u00edn Guadalupe G\u00f3mez Liz\u00e1rraga (PT) present\u00f3 el acuerdo de la Comisi\u00f3n de R\u00e9gimen Interno y Concertaci\u00f3n Pol\u00edtica (CRICP) para modificar el Acuerdo n\u00famero 87 y actualizar la integraci\u00f3n de la Comisi\u00f3n de Administraci\u00f3n, derivado de los cambios en la coordinaci\u00f3n del Grupo Parlamentario de Nueva Alianza Sonora. Como parte de esta modificaci\u00f3n, el diputado C\u00e9sar Adalberto Salazar L\u00f3pez dej\u00f3 de integrar dicha comisi\u00f3n y, en su lugar, se incorpor\u00f3 la diputada Rebeca Irene Silva Gallardo (NAS). Adicionalmente, el diputado Salazar L\u00f3pez asumi\u00f3 la coordinaci\u00f3n del Grupo Parlamentario de Nueva Alianza Sonora.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295-1024x682.png\" alt=\"\" class=\"wp-image-4111\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-295.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la diputada Rebeca Irene Silva Gallardo (NAS) ley\u00f3 ante el Pleno el dictamen de la Comisi\u00f3n de Gobernaci\u00f3n y Puntos Constitucionales sobre la Ley de Mecanismos Alternativos de Soluci\u00f3n de Controversias para el Estado de Sonora, que establece un nuevo marco jur\u00eddico para fortalecer la mediaci\u00f3n, conciliaci\u00f3n y otros mecanismos alternativos de soluci\u00f3n de conflictos en la entidad, con el fin de agilizar la impartici\u00f3n de justicia y fomentar acuerdos entre las partes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293-1024x682.png\" alt=\"\" class=\"wp-image-4109\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-293.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, la diputada Karina Mar\u00eda Olivares R\u00e1bago (PES) present\u00f3 el dictamen de la Comisi\u00f3n de Seguridad Ciudadana que contiene el decreto mediante el cual se actualizan las disposiciones que regulan la actuaci\u00f3n de las instituciones policiales en el uso de la fuerza p\u00fablica, con el objetivo de fortalecer los principios de legalidad, proporcionalidad y respeto a los derechos humanos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289-1024x682.png\" alt=\"\" class=\"wp-image-4105\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-289.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Marcela Valenzuela Nev\u00e1rez (Morena) present\u00f3 el decreto que adiciona diversas disposiciones a la Ley de los Derechos de Ni\u00f1as, Ni\u00f1os y Adolescentes, con el prop\u00f3sito de evitar la revictimizaci\u00f3n de este sector mediante su m\u00ednima intervenci\u00f3n en procesos judiciales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288-1024x682.png\" alt=\"\" class=\"wp-image-4104\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-288.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Enseguida, la diputada Claudia Zulema Bours Corral (PVEM) present\u00f3 el decreto de reforma al C\u00f3digo Penal y a la Ley de Acceso de las Mujeres a una Vida Libre de Violencia para el Estado de Sonora, mediante el cual se tipifica el acecho como delito cuando exista hostigamiento, vigilancia o contacto reiterado que afecte la seguridad e integridad de las v\u00edctimas, adem\u00e1s de fortalecer las medidas para prevenir y sancionar la violencia contra las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Elia Sahara Sallard Hern\u00e1ndez (Morena) present\u00f3 el dictamen de la Comisi\u00f3n de Justicia y Derechos Humanos que reforma diversas disposiciones del C\u00f3digo Penal del Estado de Sonora para establecer la imprescriptibilidad de los delitos sexuales cometidos contra ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298-1024x682.png\" alt=\"\" class=\"wp-image-4114\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-298.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nombre del Grupo Parlamentario del PRI, el diputado Emeterio Ochoa Baz\u00faa present\u00f3 una iniciativa de reforma a la Ley Org\u00e1nica del Poder Judicial del Estado de Sonora, con el objetivo de garantizar el acceso efectivo a la justicia para personas sordas y con discapacidad auditiva, mediante la incorporaci\u00f3n de int\u00e9rpretes de Lengua de Se\u00f1as Mexicana, capacitaci\u00f3n judicial, herramientas tecnol\u00f3gicas accesibles y medidas permanentes de inclusi\u00f3n y accesibilidad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297-1024x682.png\" alt=\"\" class=\"wp-image-4113\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297-1024x682.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297-1536x1023.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-297.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Justicia y Derechos Humanos para su an\u00e1lisis y, en su caso, dictaminaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300-1024x518.png\" alt=\"\" class=\"wp-image-4116\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300-1024x518.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300-300x152.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300-768x388.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300-1536x777.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/05\/image-300.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u2022 Rinde protesta Eduardo Quiroga Jim\u00e9nez como diputado de la 64 Legislatura Hermosillo, Sonora; 22 de mayo de 2026.- En sesi\u00f3n extraordinaria, el Congreso del Estado de Sonora aprob\u00f3 diversas reformas e iniciativas en materia de austeridad republicana, acceso a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-4101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4101"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4101\/revisions"}],"predecessor-version":[{"id":4117,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4101\/revisions\/4117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/4115"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}