{"id":4321,"date":"2026-06-02T20:33:54","date_gmt":"2026-06-03T03:33:54","guid":{"rendered":"https:\/\/sonoracomunicaciones.mx\/?p=4321"},"modified":"2026-06-02T20:34:02","modified_gmt":"2026-06-03T03:34:02","slug":"sistema-salva-avanza-en-acciones-para-prevenir-y-atender-la-violencia-familiar-en-sonora","status":"publish","type":"post","link":"https:\/\/sonoracomunicaciones.mx\/index.php\/2026\/06\/02\/sistema-salva-avanza-en-acciones-para-prevenir-y-atender-la-violencia-familiar-en-sonora\/","title":{"rendered":"Sistema SALVA avanza en acciones para prevenir y atender la violencia familiar en Sonora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nogales, Sonora; 2 de junio de 2026.- Con acciones constantes del Sistema de Atenci\u00f3n a la Violencia Familiar y de G\u00e9nero (SALVA) de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), durante la presente semana se capacit\u00f3 a polic\u00edas municipales en Nogales, servidores p\u00fablicos del Ayuntamiento de Guaymas y se instalaron lugares seguros en Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el compromiso de llegar al mayor n\u00famero de sonorenses con informaci\u00f3n de utilidad para prevenir violencias, principalmente contra la mujer, el Sistema SALVA realiza jornadas intensivas de trabajo en municipios de Sonora.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22-1024x683.png\" alt=\"\" class=\"wp-image-4323\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22-1024x683.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22-300x200.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22-768x512.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22-1536x1024.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-22.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zulema Boneo Silva, coordinadora estatal del Sistema SALVA, inform\u00f3 que, durante la semana, colabor\u00f3 con el Ayuntamiento de Nogales para sensibilizar a las y los elementos de Seguridad P\u00fablica, ante su responsabilidad como Primer Respondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Receptivos y con gran inter\u00e9s de contribuir a brindar seguridad a las mujeres, integrantes de la corporaci\u00f3n reciben adiestramiento especializado para que cada reporte sea atendido sin excepci\u00f3n, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria indic\u00f3 que en Guaymas se orient\u00f3 a servidores p\u00fablicos municipales sobre los protocolos para prevenir, atender y dar seguimiento a v\u00edctimas de violencia familiar y de g\u00e9nero, concientiz\u00e1ndolos sobre la importancia de actuar de forma inmediata ante cualquier signo de alerta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23-1024x768.png\" alt=\"\" class=\"wp-image-4324\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23-1024x768.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23-300x225.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23-768x576.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23-1536x1152.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-23.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En Hermosillo, dijo, con el objetivo de dar seguimiento y atenci\u00f3n integral a los casos de violencia familiar y de g\u00e9nero con riesgo m\u00e1s inminente, sesionaron las y los enlaces del Sistema SALVA. De igual forma, se ofreci\u00f3 pl\u00e1tica informativa a personal del Centro de Atenci\u00f3n Infantil 1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y se instal\u00f3 la Zona SALVA en las oficinas del Consejo Estatal de Concertaci\u00f3n para la Obra P\u00fablica (Cecop), ubicada en calle Ignacio Zaragoza n\u00famero 5 de la colonia Villa de Seris, C.P. 83170.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"4325\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24-1024x576.png\" alt=\"\" class=\"wp-image-4325\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24-1024x576.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24-300x169.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24-768x432.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24-1536x864.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-24.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"4326\" src=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25-1024x768.png\" alt=\"\" class=\"wp-image-4326\" srcset=\"https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25-1024x768.png 1024w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25-300x225.png 300w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25-768x576.png 768w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25-1536x1152.png 1536w, https:\/\/sonoracomunicaciones.mx\/wp-content\/uploads\/2026\/06\/image-25.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante cada capacitaci\u00f3n, se enfatiza la funci\u00f3n y protocolos de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zonas SALVA<\/li>\n\n\n\n<li>Aplicaci\u00f3n m\u00f3vil Mujeres Seguras<\/li>\n\n\n\n<li>Violent\u00f3metro<\/li>\n\n\n\n<li>C\u00f3mo reportar casos de violencia familiar a la l\u00ednea 9-1-1 o denuncia an\u00f3nima al 089.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nogales, Sonora; 2 de junio de 2026.- Con acciones constantes del Sistema de Atenci\u00f3n a la Violencia Familiar y de G\u00e9nero (SALVA) de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), durante la presente semana se capacit\u00f3 a polic\u00edas municipales&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,88],"tags":[],"class_list":["post-4321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sonora"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4321"}],"version-history":[{"count":1,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321\/revisions"}],"predecessor-version":[{"id":4327,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321\/revisions\/4327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media\/4323"}],"wp:attachment":[{"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonoracomunicaciones.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}